{"id":1170,"date":"2022-01-26T01:12:18","date_gmt":"2022-01-26T06:12:18","guid":{"rendered":"https:\/\/karoslittlecorner.wordpress.com\/?p=1170"},"modified":"2023-06-09T15:24:36","modified_gmt":"2023-06-09T19:24:36","slug":"comment-rester-confiant-e-et-sereine-quand-tout-seffondre","status":"publish","type":"post","link":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/","title":{"rendered":"Comment rester confiant (e)\/et serein(e) quand tout s\u2019effondre"},"content":{"rendered":"\r\n<p class=\"has-text-align-center\" style=\"text-align: center;\"><em><strong>Bonjour \u00e0 tous et bienvenue sur mon blog. Encore une fois, malgr\u00e9 que nous sommes \u00e0 la fin du mois de janvier je pense qu\u2019il n\u2019est pas superflu de souhaiter \u00e0 chacun \/ chacune une bonne et heureuse ann\u00e9e 2022. Que cette nouvelle ann\u00e9e vous apporte beaucoup de joie et de b\u00e9n\u00e9dictions. Mon premier article pour cette nouvelle ann\u00e9e servira de petit coup de pouce ou de motivation pour tous ceux\/celles qui traversent une p\u00e9riode assez difficile\/stressante.<\/strong><\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">Ces derni\u00e8res semaines ont \u00e9t\u00e9 difficiles pour moi. Depuis mon retour, je suis \u00e0 la recherche d\u2019un emploi et malheureusement j\u2019ai \u00e9t\u00e9 rejet\u00e9e apr\u00e8s chaque application. Je n\u2019ai que deux exp\u00e9riences professionnelles et pour ces deux emplois, j\u2019ai \u00e9t\u00e9 accept\u00e9e en un clin d\u2019\u0153il donc ce genre de refus ne m\u2019est pas familier. Pour la premi\u00e8re fois, j\u2019ai commenc\u00e9 \u00e0 douter de mes comp\u00e9tences et de mes capacit\u00e9s. Je me suis dit que je ne suis peut-\u00eatre pas assez dou\u00e9e. Cette situation a eu un impact sur ma sant\u00e9 mentale et je sais que je ne suis pas la seule \u00e0 vivre cela. Par cons\u00e9quent, aujourd\u2019hui nous allons voir pourquoi il est primordial de rester serein pendant ces moments difficiles. Ainsi je partage avec vous quelques conseils.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>1. N\u2019ayez pas d\u2019attentes irr\u00e9alistes<\/strong>. C\u2019est exactement ce qui m\u2019est arriv\u00e9. Je suis tomb\u00e9e dans le pi\u00e8ge. J\u2019ai toujours pens\u00e9 que j\u2019obtiendrais automatiquement un emploi apr\u00e8s avoir termin\u00e9 mes \u00e9tudes parce que j\u2019\u00e9tais une \u00e9tudiante assez brillante et que j\u2019avais un tas de certificats. J\u2019ai toujours cru en mes capacit\u00e9s et mes comp\u00e9tences. Je pensais que n\u2019importe quel employeur serait impressionn\u00e9 par mon CV et n\u2019importe quelle compagnie serait fortun\u00e9e de me compter parmi ses employ\u00e9s. Evitez d\u2019avoir des attentes que vous savez au fond de vous sont irr\u00e9alistes.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>2. Ayez confiance en vous.<\/strong> L\u2019\u00e9chec ne d\u00e9finit pas qui vous \u00eates et ce dont vous \u00eates capable. Tombez 10 fois, relevez-vous 20 fois. Peut-\u00eatre que la raison pour laquelle vous avez \u00e9t\u00e9 rejet\u00e9 pour l\u2019offre d\u2019emploi est parce que vous \u00eates surqualifi\u00e9 et non parce que vous manquez de comp\u00e9tences.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>3. Les bonnes choses prennent du temps<\/strong>. On dit toujours que les vins se bonifient avec le temps. Eh bien, c\u2019est ainsi qu\u2019il faut voir la vie. Les meilleures r\u00e9compenses prennent du temps pour se concr\u00e9tiser. Certaines personnes peuvent trouver le travail de leurs r\u00eaves juste apr\u00e8s l\u2019universit\u00e9, pour d\u2019autres, cela peut prendre des ann\u00e9es. Nous sommes tous diff\u00e9rents et nous n\u2019avons pas le m\u00eame destin.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>4.La vie est trop courte<\/strong>. La vie est beaucoup trop courte, tout peut dispara\u00eetre en un clin d\u2019\u0153il. Ne passez pas votre temps \u00e0 vous attarder sur le pass\u00e9 et sur vos \u00e9checs. Concentrez-vous sur les le\u00e7ons apprises et sur la fa\u00e7on dont vous les appliquerez \u00e0 partir de maintenant.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>5. La temp\u00eate ne durera pas<\/strong>. Respirez!! De meilleurs jours sont \u00e0 venir. Le nuage noir dispara\u00eetra bient\u00f4t et le soleil brillera. Soyez patient et plein d\u2019espoir.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>6. Tout se passe pour une raison.<\/strong> La phrase est claire et compr\u00e9hensible. M\u00eame si tout peut sembler d\u00e9routant et injuste maintenant, je suis s\u00fbre qu\u2019il y a une bonne explication et une bonne raison. Acceptez le fait que vous n\u2019auriez rien pu faire pour \u00e9viter cette situation et concentrez-vous plut\u00f4t sur la fa\u00e7on de vous en sortir.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>7. Prenez soin de vous<\/strong>. En traversant une p\u00e9riode difficile, il est n\u00e9cessaire de vous rappeler que vous avez de la valeur, votre sant\u00e9 compte \u00e9galement. Prenez du temps pour vous, loin de tout le monde. Concentrez-vous sur ce qui peut apaiser votre esprit et vous aider \u00e0 vous d\u00e9tendre : comme la lecture , le yoga, la promenade, le sport\u2026 Cela vous aidera \u00e0 oublier vos probl\u00e8mes et \u00e0 soulager votre stress.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>8. Tenez-vous occup\u00e9<\/strong>. En attendant cet appel t\u00e9l\u00e9phonique ou cet email qui changera le court de votre vie, faites quelque chose de productif. Apprenez quelque chose de nouveau ou trouvez un endroit pour faire du b\u00e9n\u00e9volat par exemple. Rendez-vous utile. Cela vous aidera \u00e0 prendre conscience de votre valeur.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>9.Pr\u00e9parez-vous<\/strong>. Lorsque vous faites face \u00e0 une situation stressante comme par exemple l\u2019attente d\u2019un appel important pour un entretien d\u2019embauche, pensez au r\u00e9sultat. Et s\u2019ils vous appellent aujourd\u2019hui, \u00eates-vous pr\u00eat \u00e0 participer et \u00e0 r\u00e9ussir l\u2019entretien ? Probablement pas. Prenez le temps de vous pr\u00e9parer et de travailler sur vos faiblesses.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>10. Priez et remettez votre cause \u00e0 Dieu<\/strong>. Quoi que vous fassiez dans la vie, mettez toujours Dieu au centre. Je crois fermement au destin. Rien dans la vie n\u2019est un hasard. Dieu sait ce qu\u2019Il fait, nous devons juste rester calmes et Lui faire confiance. C\u2019est normal qu\u2019en ce moment pr\u00e9sent nous ne comprenions pas pourquoi nous traversons cette \u00e9preuve, mais c\u2019est peut-\u00eatre Sa fa\u00e7on \u00e0 lui de nous prot\u00e9ger d\u2019un potentiel danger.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-center\" style=\"text-align: center;\"><em><strong>C\u2019est tout pour aujourd\u2019hui. Merci \u00e0 tous de toujours garder une certaine confiance en moi. S\u2019il y en a, parmi mes fid\u00e8les lecteurs qui traversent une p\u00e9riode similaire, assez stressante, je prie pour que Dieu jette Son regard bienveillant sur tout un chacun. Gardez la t\u00eate haute. En attendant la prochaine publication, restez en s\u00e9curit\u00e9 et soyez b\u00e9nis\u2026!!<\/strong><\/em><\/p>\r\n<p class=\"has-text-align-center\" style=\"text-align: center;\"><em>(PS: je m\u2019en voudrais de ne pas vous annoncer qu\u2019 en terminant l\u2019article, je viens tout juste de recevoir un appel m\u2019invitant \u00e0 une entrevue pour un nouveau poste. Attendons de voir<\/em>)<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Bonjour \u00e0 tous et bienvenue sur mon blog. Encore une fois, malgr\u00e9 que nous sommes \u00e0 la fin du mois de janvier je pense qu\u2019il n\u2019est pas superflu de souhaiter \u00e0 chacun \/ chacune une bonne et heureuse ann\u00e9e 2022. Que cette nouvelle ann\u00e9e vous apporte beaucoup de joie et de b\u00e9n\u00e9dictions. Mon premier article [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":{"0":"post-1170","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-traduction-francaise"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment rester confiant (e)\/et serein(e) quand tout s\u2019effondre -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment rester confiant (e)\/et serein(e) quand tout s\u2019effondre -\" \/>\n<meta property=\"og:description\" content=\"Bonjour \u00e0 tous et bienvenue sur mon blog. Encore une fois, malgr\u00e9 que nous sommes \u00e0 la fin du mois de janvier je pense qu\u2019il n\u2019est pas superflu de souhaiter \u00e0 chacun \/ chacune une bonne et heureuse ann\u00e9e 2022. Que cette nouvelle ann\u00e9e vous apporte beaucoup de joie et de b\u00e9n\u00e9dictions. Mon premier article [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-26T06:12:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-09T19:24:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"karoaug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"karoaug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/01\\\/26\\\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/01\\\/26\\\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\\\/\"},\"author\":{\"name\":\"karoaug\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"headline\":\"Comment rester confiant (e)\\\/et serein(e) quand tout s\u2019effondre\",\"datePublished\":\"2022-01-26T06:12:18+00:00\",\"dateModified\":\"2023-06-09T19:24:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/01\\\/26\\\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\\\/\"},\"wordCount\":946,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"image\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/01\\\/26\\\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/pexels-energepiccom-313690-scaled.webp?fit=2560%2C1920&ssl=1\",\"articleSection\":[\"Traduction fran\u00e7aise\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/01\\\/26\\\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/01\\\/26\\\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\\\/\",\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/01\\\/26\\\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\\\/\",\"name\":\"Comment rester confiant (e)\\\/et serein(e) quand tout s\u2019effondre -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/01\\\/26\\\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/01\\\/26\\\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/pexels-energepiccom-313690-scaled.webp?fit=2560%2C1920&ssl=1\",\"datePublished\":\"2022-01-26T06:12:18+00:00\",\"dateModified\":\"2023-06-09T19:24:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/01\\\/26\\\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/01\\\/26\\\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/01\\\/26\\\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/pexels-energepiccom-313690-scaled.webp?fit=2560%2C1920&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/pexels-energepiccom-313690-scaled.webp?fit=2560%2C1920&ssl=1\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/01\\\/26\\\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/karoslittlecorner.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment rester confiant (e)\\\/et serein(e) quand tout s\u2019effondre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#website\",\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/\",\"name\":\"karoslittlecorner\",\"description\":\"Karo&#039;s blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/karoslittlecorner.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\",\"name\":\"karoaug\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"karoaug\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\"},\"sameAs\":[\"https:\\\/\\\/karoslittlecorner.com\"],\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/author\\\/karoaug\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment rester confiant (e)\/et serein(e) quand tout s\u2019effondre -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/","og_locale":"en_US","og_type":"article","og_title":"Comment rester confiant (e)\/et serein(e) quand tout s\u2019effondre -","og_description":"Bonjour \u00e0 tous et bienvenue sur mon blog. Encore une fois, malgr\u00e9 que nous sommes \u00e0 la fin du mois de janvier je pense qu\u2019il n\u2019est pas superflu de souhaiter \u00e0 chacun \/ chacune une bonne et heureuse ann\u00e9e 2022. Que cette nouvelle ann\u00e9e vous apporte beaucoup de joie et de b\u00e9n\u00e9dictions. Mon premier article [&hellip;]","og_url":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/","article_published_time":"2022-01-26T06:12:18+00:00","article_modified_time":"2023-06-09T19:24:36+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp","type":"image\/jpeg"}],"author":"karoaug","twitter_card":"summary_large_image","twitter_misc":{"Written by":"karoaug","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/#article","isPartOf":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/"},"author":{"name":"karoaug","@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"headline":"Comment rester confiant (e)\/et serein(e) quand tout s\u2019effondre","datePublished":"2022-01-26T06:12:18+00:00","dateModified":"2023-06-09T19:24:36+00:00","mainEntityOfPage":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/"},"wordCount":946,"commentCount":3,"publisher":{"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"image":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?fit=2560%2C1920&ssl=1","articleSection":["Traduction fran\u00e7aise"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/","url":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/","name":"Comment rester confiant (e)\/et serein(e) quand tout s\u2019effondre -","isPartOf":{"@id":"https:\/\/karoslittlecorner.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/#primaryimage"},"image":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?fit=2560%2C1920&ssl=1","datePublished":"2022-01-26T06:12:18+00:00","dateModified":"2023-06-09T19:24:36+00:00","breadcrumb":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/#primaryimage","url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?fit=2560%2C1920&ssl=1","contentUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?fit=2560%2C1920&ssl=1","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/01\/26\/comment-rester-confiant-e-et-sereine-quand-tout-seffondre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/karoslittlecorner.com\/"},{"@type":"ListItem","position":2,"name":"Comment rester confiant (e)\/et serein(e) quand tout s\u2019effondre"}]},{"@type":"WebSite","@id":"https:\/\/karoslittlecorner.com\/#website","url":"https:\/\/karoslittlecorner.com\/","name":"karoslittlecorner","description":"Karo&#039;s blog","publisher":{"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/karoslittlecorner.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909","name":"karoaug","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"karoaug"},"logo":{"@id":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1"},"sameAs":["https:\/\/karoslittlecorner.com"],"url":"https:\/\/karoslittlecorner.com\/index.php\/author\/karoaug\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?fit=2560%2C1920&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?fit=2560%2C1920&ssl=1",2560,1920,false],"thumbnail":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?fit=300%2C225&ssl=1",300,225,true],"medium_large":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?fit=768%2C576&ssl=1",768,576,true],"large":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?fit=700%2C525&ssl=1",700,525,true],"1536x1536":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?fit=1536%2C1152&ssl=1",1536,1152,true],"2048x2048":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?fit=2048%2C1536&ssl=1",2048,1536,true],"pixwell_370x250":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?resize=370%2C250&ssl=1",370,250,true],"pixwell_370x250-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?resize=740%2C500&ssl=1",740,500,true],"pixwell_370x250-3x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?resize=1110%2C750&ssl=1",1110,750,true],"pixwell_280x210":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?resize=280%2C210&ssl=1",280,210,true],"pixwell_280x210-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?resize=560%2C420&ssl=1",560,420,true],"pixwell_400x450":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?resize=400%2C450&ssl=1",400,450,true],"pixwell_400x600":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?resize=400%2C600&ssl=1",400,600,true],"pixwell_450x0":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?resize=450%2C338&ssl=1",450,338,true],"pixwell_780x0":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?resize=780%2C585&ssl=1",780,585,true],"pixwell_780x0-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?resize=1600%2C1200&ssl=1",1600,1200,true],"mailpoet_newsletter_max":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/01\/pexels-energepiccom-313690-scaled.webp?fit=1320%2C990&ssl=1",1320,990,true]},"uagb_author_info":{"display_name":"karoaug","author_link":"https:\/\/karoslittlecorner.com\/index.php\/author\/karoaug\/"},"uagb_comment_info":23,"uagb_excerpt":"Bonjour \u00e0 tous et bienvenue sur mon blog. Encore une fois, malgr\u00e9 que nous sommes \u00e0 la fin du mois de janvier je pense qu\u2019il n\u2019est pas superflu de souhaiter \u00e0 chacun \/ chacune une bonne et heureuse ann\u00e9e 2022. Que cette nouvelle ann\u00e9e vous apporte beaucoup de joie et de b\u00e9n\u00e9dictions. Mon premier article&hellip;","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/1170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/comments?post=1170"}],"version-history":[{"count":2,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/1170\/revisions"}],"predecessor-version":[{"id":2859,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/1170\/revisions\/2859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/media\/2608"}],"wp:attachment":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/media?parent=1170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/categories?post=1170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/tags?post=1170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}