{"id":1381,"date":"2022-09-15T22:46:25","date_gmt":"2022-09-16T02:46:25","guid":{"rendered":"https:\/\/karoslittlecorner.wordpress.com\/?p=1381"},"modified":"2023-06-09T15:18:47","modified_gmt":"2023-06-09T19:18:47","slug":"10-choses-que-tu-dois-faire-aujourdhui","status":"publish","type":"post","link":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/","title":{"rendered":"10 choses que tu dois faire aujourd\u2019hui"},"content":{"rendered":"\r\n<p class=\"has-text-align-center\" style=\"text-align: center;\"><em><strong>Bonjour\/Bonsoir \u00e0 tous et bienvenue sur mon blog! J\u2019esp\u00e8re que tout le monde se porte bien. Je suis de retour avec un autre article aujourd\u2019hui et j\u2019esp\u00e8re que vous allez l\u2019appr\u00e9cier. N\u2019oubliez pas de suivre mon blog, et de partager l\u2019article avec vos proches et amis.<\/strong><\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">Durant ces derni\u00e8res ann\u00e9es, le monde s\u2019est transform\u00e9 en un endroit si terrifiant, cruel et horrible. Avec tout ce qui se passe dans des pays tels que l\u2019Ukraine, le Pakistan et plus pr\u00e8s de nous en Ha\u00efti: violence, guerre, inondations, famine, massacres, fusillades, etc., il est facile pour quiconque de se sentir traumatis\u00e9, anxieux et d\u00e9prim\u00e9. Si vous avez l\u2019habitude de lire mon blog, c\u2019est s\u00fbr que vous avez remarqu\u00e9 que j\u2019accorde beaucoup d\u2019importance au bien-\u00eatre et \u00e0 la sant\u00e9 mentale. C\u2019est dans cette optique que je pense qu\u2019il est important aujourd\u2019hui, de prendre du temps et de faire ces 10 choses.<\/p>\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large\" style=\"text-align: justify;\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-1403 size-large\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6498-1.jpg?resize=700%2C683&ssl=1\" alt=\"\" width=\"700\" height=\"683\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6498-1.jpg?resize=1024%2C999&ssl=1 1024w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6498-1.jpg?resize=300%2C293&ssl=1 300w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6498-1.jpg?resize=768%2C750&ssl=1 768w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6498-1.jpg?resize=900%2C878&ssl=1 900w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6498-1.jpg?w=1170&ssl=1 1170w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n<p style=\"text-align: justify;\"><strong>1. Prenez une profonde respiration. <\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">Parfois, nous sommes tellement concentr\u00e9s \u00e0 bien faire tout ce qu\u2019on entreprend, et si vous \u00eates en Ha\u00efti, o\u00f9 chacun essaye de survivre, que nous oublions souvent de prendre le temps de respirer un peu. Hier, nous avons v\u00e9cu une exp\u00e9rience terrible. On a d\u00fb passer plus de quatre heures \u00e0 plat sur le sol en raison des tirs nourris de toute part dans le quartier. Nous \u00e9tions tellement concentr\u00e9s sur le fait de survivre et ne pas \u00eatre abattus qu\u2019\u00e0 un moment donn\u00e9, je n\u2019ai m\u00eame plus pens\u00e9 \u00e0 prendre le temps de respirer. En ce moment m\u00eame, arr\u00eatez ce que vous faites et prenez du temps pour inspirer \u00e0 fond et expirer. Vous vous sentirez un peu d\u00e9tendu apr\u00e8s cet exercice.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><strong>2. Faites quelque chose que vous aimez. <\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">Qu\u2019est-ce qui vous vient \u00e0 l\u2019id\u00e9e lorsque vous lisez le # 2? Si on vous demande de choisir une chose que vous aimez faire , qu\u2019auriez-vous choisi ? Personnellement, j\u2019aime \u00e9crire et j\u2019aime aussi jouer de la musique. Pour \u00eatre honn\u00eate, je ne sais m\u00eame plus o\u00f9 se trouve ma guitare en ce moment. Je ne me rappelle m\u00eame pas de la derni\u00e8re fois que j\u2019ai pris ma guitare pour jouer quelques morceaux. Faire quelque chose qu\u2019on aime peut nous aider \u00e0 soulager le stress et \u00e0 changer positivement notre humeur. Alors faites-le!<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><strong>3. Dites \u00e0 quelqu\u2019un que vous l\u2019aimez. <\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">Nous avons tous des gens proches de nous pour lesquels nous sommes reconnaissants mais nous omettons toujours de le leur dire. C\u2019est totalement compr\u00e9hensible parce que tout le monde n\u2019a pas le m\u00eame langage d\u2019amour. Si votre langage d\u2019amour n\u2019a pas en substance les \u201cparoles valorisantes \u201c, vous ne comprendrez pas pourquoi c\u2019est n\u00e9cessaire de dire aux gens qu\u2019on les aime. J\u2019ai perdu tellement de personnes importantes dans le pass\u00e9 et l\u2019un de mes regrets est de ne pas avoir exprim\u00e9 mon appr\u00e9ciation et mon amour pour elles. Ne commettez pas la m\u00eame erreur que moi. La vie est tellement impr\u00e9visible, envoyez un petit texto \u00e0 un proche aujourd\u2019hui pour lui dire que vous l\u2019appr\u00e9ciez et que vous l\u2019aimez beaucoup.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><strong>4. Parlez \u00e0 quelqu\u2019un. <\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">L\u2019une des meilleures th\u00e9rapies lorsqu\u2019on traverse une p\u00e9riode difficile est le d\u00e9foulement (psychologique). Trouvez quelqu\u2019un en qui vous avez confiance, quelqu\u2019un qui souhaite vous offrir une oreille pour vous \u00e9couter et lib\u00e9rez vous de tout ce qui vous pr\u00e9occupe. Vous aurez par la suite l\u2019impression qu\u2019un poids a \u00e9t\u00e9 soulev\u00e9 de vos \u00e9paules.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><strong>5. Ne vous engagez pas dans des disputes inutiles. <\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">Pour prot\u00e9ger votre tranquillit\u00e9 d\u2019esprit, \u00e9vitez d\u2019alimenter les disputes inutiles. Certaines personnes vivent de cela. Elles aiment les disputes et cherchent toujours la petite b\u00eate pour en d\u00e9clencher une. Je les consid\u00e8re comme des ennemis de la paix. Supprime ce message que tu allais envoyer, r\u00e9ponds simplement par \u00abd\u2019accord\u00bb et passe \u00e0 autre chose. Bien que je sais que la communication est la cl\u00e9, mais dans ces moments, parfois \u00e7a ne vaut pas la peine.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><strong>6. Dites vos affirmations quotidiennes.<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">\u201c<em>Les affirmations positives sont des d\u00e9clarations sp\u00e9cifiques qui vous aident \u00e0 surmonter les pens\u00e9es n\u00e9gatives.<\/em>\u201d Je commence toujours mes affirmations par \u201cJe suis \u2026\u201d puis je compl\u00e8te la phrase. Trouvez au moins 3 affirmations aujourd\u2019hui. Je sais que ce n\u2019est pas facile, mais pendant les p\u00e9riodes difficiles, je r\u00e9p\u00e8te toujours \u201cJe suis forte et je vais surmonter tout \u00e7a!\u201d ou j\u2019\u00e9cris tout simplement mon affirmation dans mon journal. Cela m\u2019aide \u00e0 me rappeler qui je suis et que rien ne peut me briser. Les affirmations positives quotidiennes nous aident \u00e0 am\u00e9liorer notre \u00e9tat d\u2019esprit et nous encouragent \u00e0 croire en un avenir meilleur.<\/p>\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-full\" style=\"text-align: justify;\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-1408 aligncenter\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6532.jpg?w=1170&ssl=1\" alt=\"\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n<p style=\"text-align: justify;\"><strong>7. Soyez reconnaissant.<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">\u201c<em>La gratitude favorise l\u2019optimisme et nous aide \u00e0 d\u00e9velopper une perspective plus positive<\/em>.\u201d De quoi \/ De qui \u00eates-vous reconnaissant aujourd\u2019hui? Prenez le temps de r\u00e9fl\u00e9chir \u00e0 cela. Durant les jours les plus sombres, il y a toujours quelque chose de positif \u00e0 rechercher; quelque chose ou quelqu\u2019un qui rend la vie digne d\u2019\u00eatre v\u00e9cue. Comme je l\u2019ai dit dans mon article sur la gratitude, le fait d\u2019\u00eatre reconnaissant et de dire merci nous rend plus heureux. Donc, remerciez quelqu\u2019un pour sa pr\u00e9sence dans votre vie ou pour toute autre raison importante. Si vous aimez mes articles vous pouvez aussi me laisser un petit mot (je blague \ud83d\ude0b).<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><strong>8. Allez au lit t\u00f4t. <\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">Une bonne nuit de sommeil est souvent le rem\u00e8de \u00e0 tous les probl\u00e8mes. Le stress et l\u2019anxi\u00e9t\u00e9 nous emp\u00eachent de dormir la nuit. Les chercheurs ont constat\u00e9 que \u201c<em>un manque de sommeil est particuli\u00e8rement n\u00e9faste pour la consolidation de contenu \u00e9motionnel positif<\/em>\u201c. Avez-vous r\u00e9alis\u00e9 que lorsque vous ne dormez pas suffisamment le soir, le lendemain, vous \u00eates de tr\u00e8s mauvaise humeur, tout vous tape sur les nerfs? D\u00e9finissez une heure et une fois que l\u2019alarme sonne, d\u00e9posez le t\u00e9l\u00e9phone et essayez de dormir. Cela aidera.<\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><strong>9. Buvez beaucoup d\u2019eau. <\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">Si mes amies du secondaire lisent ceci, elles se moqueront de moi. Petite histoire : Autrefois, je n\u2019aimais pas boire de l\u2019eau. Je pouvais passer des jours sans boire un verre entier. Au secondaire, presque tout le monde avait ces \u00e9normes bouteilles d\u2019eau sauf moi, je n\u2019avais qu\u2019une petite bouteille juste pour le jus. Un jour, un de mes m\u00e9decins m\u2019a expliqu\u00e9 les probl\u00e8mes qu\u2019on peut rencontrer lorsqu\u2019on ne boit pas assez d\u2019eau, ce n\u2019\u00e9tait toujours pas suffisant pour me convaincre. J\u2019avais l\u2019habitude de voir ma belle-soeur boire un gallon d\u2019eau tous les jours et je ne pouvais pas comprendre comment elle y parvenait. Enfin, j\u2019ai d\u00e9cid\u00e9 d\u2019acheter une de ces bouteilles tr\u00e8s color\u00e9es avec les heures inscrites dessus pour vous rappeler de boire pendant la journ\u00e9e, juste parce qu\u2019elles \u00e9taient tr\u00e8s attirantes. Je savais au fond de moi que je ne pourrais jamais boire le contenu de la bouteille. Aujourd\u2019hui, je bois 3 L d\u2019eau tous les jours et parfois plus que cela et je ne me suis jamais sentie mieux. Tout \u00e7a pour vous dire que peu importe ce qui se passe dans votre vie, il est important de garder le corps hydrat\u00e9. <em>Dans une \u00e9tude r\u00e9alis\u00e9e en 2018, sur plus de 3 000 adultes, ceux qui buvaient plus d\u2019eau avaient un risque plus faible d\u2019anxi\u00e9t\u00e9 et de d\u00e9pression que ceux qui n\u2019en buvaient pas. <\/em><sup><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6147771\/\">1<\/a><\/sup><\/p>\r\n\r\n\r\n\r\n<p style=\"text-align: justify;\"><strong>10. Priez. <\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">Dernier point mais non le moins important, prenez le temps de parler \u00e0 Dieu. Les temps difficiles ont tendance \u00e0 tester notre foi. La plupart du temps, durant les situations stressantes, nous sommes tellement consomm\u00e9s par notre liste d\u2019inqui\u00e9tudes que nous oublions \u00e0 quel point Dieu est grand. Si vous ne l\u2019avez jamais v\u00e9cu, vous ne comprendrez certainement pas le pouvoir d\u2019une pri\u00e8re. N\u2019oubliez pas qu\u2019une longue pri\u00e8re n\u2019est pas synonyme d\u2019efficacit\u00e9. La pri\u00e8re peut \u00eatre aussi simple qu\u2019une phrase. Mes parents m\u2019ont toujours appris qu\u2019\u00e0 chaque fois que j\u2019ai l\u2019impression de ne pas savoir quoi dire dans une pri\u00e8re, de r\u00e9p\u00e9ter simplement la phrase de Barthim\u00e9e : \u201cJ\u00e9sus, fils de David, aie piti\u00e9 de moi.\u201d Garder la foi pendant p\u00e9riode difficile peut nous permettre de trouver la paix en pr\u00e9sence de Dieu.<\/p>\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large\" style=\"text-align: justify;\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-1406 size-large\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6531.png?resize=700%2C700&ssl=1\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6531.png?w=1024&ssl=1 1024w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6531.png?resize=300%2C300&ssl=1 300w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6531.png?resize=150%2C150&ssl=1 150w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6531.png?resize=768%2C768&ssl=1 768w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6531.png?resize=88%2C88&ssl=1 88w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/img_6531.png?resize=900%2C900&ssl=1 900w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n<p class=\"has-text-align-center\" style=\"text-align: center;\"><em><strong>C\u2019est tout pour aujourd\u2019hui. J\u2019esp\u00e8re que vous avez pris du plaisir \u00e0 lire cet article autant que j\u2019ai pris du plaisir \u00e0 l\u2019\u00e9crire. Assurez-vous de d\u2019appliquer au moins 3 de ces astuces aujourd\u2019hui, je vous en supplie. En attendant la prochaine publication, restez en s\u00e9curit\u00e9 et soyez b\u00e9nis\u2026. toujours !!<\/strong><\/em><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Bonjour\/Bonsoir \u00e0 tous et bienvenue sur mon blog! J\u2019esp\u00e8re que tout le monde se porte bien. Je suis de retour avec un autre article aujourd\u2019hui et j\u2019esp\u00e8re que vous allez l\u2019appr\u00e9cier. N\u2019oubliez pas de suivre mon blog, et de partager l\u2019article avec vos proches et amis. Durant ces derni\u00e8res ann\u00e9es, le monde s\u2019est transform\u00e9 en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":false,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":{"0":"post-1381","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-traduction-francaise"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 choses que tu dois faire aujourd\u2019hui -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 choses que tu dois faire aujourd\u2019hui -\" \/>\n<meta property=\"og:description\" content=\"Bonjour\/Bonsoir \u00e0 tous et bienvenue sur mon blog! J\u2019esp\u00e8re que tout le monde se porte bien. Je suis de retour avec un autre article aujourd\u2019hui et j\u2019esp\u00e8re que vous allez l\u2019appr\u00e9cier. N\u2019oubliez pas de suivre mon blog, et de partager l\u2019article avec vos proches et amis. Durant ces derni\u00e8res ann\u00e9es, le monde s\u2019est transform\u00e9 en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-16T02:46:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-09T19:18:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"karoaug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"karoaug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/09\\\/15\\\/10-choses-que-tu-dois-faire-aujourdhui\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/09\\\/15\\\/10-choses-que-tu-dois-faire-aujourdhui\\\/\"},\"author\":{\"name\":\"karoaug\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"headline\":\"10 choses que tu dois faire aujourd\u2019hui\",\"datePublished\":\"2022-09-16T02:46:25+00:00\",\"dateModified\":\"2023-06-09T19:18:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/09\\\/15\\\/10-choses-que-tu-dois-faire-aujourdhui\\\/\"},\"wordCount\":1469,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"image\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/09\\\/15\\\/10-choses-que-tu-dois-faire-aujourdhui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/pexels-arina-krasnikova-5712511-scaled.webp?fit=2560%2C1709&ssl=1\",\"articleSection\":[\"Traduction fran\u00e7aise\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/09\\\/15\\\/10-choses-que-tu-dois-faire-aujourdhui\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/09\\\/15\\\/10-choses-que-tu-dois-faire-aujourdhui\\\/\",\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/09\\\/15\\\/10-choses-que-tu-dois-faire-aujourdhui\\\/\",\"name\":\"10 choses que tu dois faire aujourd\u2019hui -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/09\\\/15\\\/10-choses-que-tu-dois-faire-aujourdhui\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/09\\\/15\\\/10-choses-que-tu-dois-faire-aujourdhui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/pexels-arina-krasnikova-5712511-scaled.webp?fit=2560%2C1709&ssl=1\",\"datePublished\":\"2022-09-16T02:46:25+00:00\",\"dateModified\":\"2023-06-09T19:18:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/09\\\/15\\\/10-choses-que-tu-dois-faire-aujourdhui\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/09\\\/15\\\/10-choses-que-tu-dois-faire-aujourdhui\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/09\\\/15\\\/10-choses-que-tu-dois-faire-aujourdhui\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/pexels-arina-krasnikova-5712511-scaled.webp?fit=2560%2C1709&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/pexels-arina-krasnikova-5712511-scaled.webp?fit=2560%2C1709&ssl=1\",\"width\":2560,\"height\":1709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2022\\\/09\\\/15\\\/10-choses-que-tu-dois-faire-aujourdhui\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/karoslittlecorner.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 choses que tu dois faire aujourd\u2019hui\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#website\",\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/\",\"name\":\"karoslittlecorner\",\"description\":\"Karo&#039;s blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/karoslittlecorner.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\",\"name\":\"karoaug\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"karoaug\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\"},\"sameAs\":[\"https:\\\/\\\/karoslittlecorner.com\"],\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/author\\\/karoaug\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 choses que tu dois faire aujourd\u2019hui -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/","og_locale":"en_US","og_type":"article","og_title":"10 choses que tu dois faire aujourd\u2019hui -","og_description":"Bonjour\/Bonsoir \u00e0 tous et bienvenue sur mon blog! J\u2019esp\u00e8re que tout le monde se porte bien. Je suis de retour avec un autre article aujourd\u2019hui et j\u2019esp\u00e8re que vous allez l\u2019appr\u00e9cier. N\u2019oubliez pas de suivre mon blog, et de partager l\u2019article avec vos proches et amis. Durant ces derni\u00e8res ann\u00e9es, le monde s\u2019est transform\u00e9 en [&hellip;]","og_url":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/","article_published_time":"2022-09-16T02:46:25+00:00","article_modified_time":"2023-06-09T19:18:47+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp","type":"image\/jpeg"}],"author":"karoaug","twitter_card":"summary_large_image","twitter_misc":{"Written by":"karoaug","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/#article","isPartOf":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/"},"author":{"name":"karoaug","@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"headline":"10 choses que tu dois faire aujourd\u2019hui","datePublished":"2022-09-16T02:46:25+00:00","dateModified":"2023-06-09T19:18:47+00:00","mainEntityOfPage":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/"},"wordCount":1469,"commentCount":2,"publisher":{"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"image":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?fit=2560%2C1709&ssl=1","articleSection":["Traduction fran\u00e7aise"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/","url":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/","name":"10 choses que tu dois faire aujourd\u2019hui -","isPartOf":{"@id":"https:\/\/karoslittlecorner.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/#primaryimage"},"image":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?fit=2560%2C1709&ssl=1","datePublished":"2022-09-16T02:46:25+00:00","dateModified":"2023-06-09T19:18:47+00:00","breadcrumb":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/#primaryimage","url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?fit=2560%2C1709&ssl=1","contentUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?fit=2560%2C1709&ssl=1","width":2560,"height":1709},{"@type":"BreadcrumbList","@id":"https:\/\/karoslittlecorner.com\/index.php\/2022\/09\/15\/10-choses-que-tu-dois-faire-aujourdhui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/karoslittlecorner.com\/"},{"@type":"ListItem","position":2,"name":"10 choses que tu dois faire aujourd\u2019hui"}]},{"@type":"WebSite","@id":"https:\/\/karoslittlecorner.com\/#website","url":"https:\/\/karoslittlecorner.com\/","name":"karoslittlecorner","description":"Karo&#039;s blog","publisher":{"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/karoslittlecorner.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909","name":"karoaug","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"karoaug"},"logo":{"@id":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1"},"sameAs":["https:\/\/karoslittlecorner.com"],"url":"https:\/\/karoslittlecorner.com\/index.php\/author\/karoaug\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?fit=2560%2C1709&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?fit=2560%2C1709&ssl=1",2560,1709,false],"thumbnail":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?fit=768%2C513&ssl=1",768,513,true],"large":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?fit=700%2C467&ssl=1",700,467,true],"1536x1536":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?fit=1536%2C1025&ssl=1",1536,1025,true],"2048x2048":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?fit=2048%2C1367&ssl=1",2048,1367,true],"pixwell_370x250":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?resize=370%2C250&ssl=1",370,250,true],"pixwell_370x250-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?resize=740%2C500&ssl=1",740,500,true],"pixwell_370x250-3x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?resize=1110%2C750&ssl=1",1110,750,true],"pixwell_280x210":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?resize=280%2C210&ssl=1",280,210,true],"pixwell_280x210-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?resize=560%2C420&ssl=1",560,420,true],"pixwell_400x450":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?resize=400%2C450&ssl=1",400,450,true],"pixwell_400x600":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?resize=400%2C600&ssl=1",400,600,true],"pixwell_450x0":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?resize=450%2C300&ssl=1",450,300,true],"pixwell_780x0":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?resize=780%2C521&ssl=1",780,521,true],"pixwell_780x0-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?resize=1600%2C1068&ssl=1",1600,1068,true],"mailpoet_newsletter_max":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2022\/09\/pexels-arina-krasnikova-5712511-scaled.webp?fit=1320%2C881&ssl=1",1320,881,true]},"uagb_author_info":{"display_name":"karoaug","author_link":"https:\/\/karoslittlecorner.com\/index.php\/author\/karoaug\/"},"uagb_comment_info":15,"uagb_excerpt":"Bonjour\/Bonsoir \u00e0 tous et bienvenue sur mon blog! J\u2019esp\u00e8re que tout le monde se porte bien. Je suis de retour avec un autre article aujourd\u2019hui et j\u2019esp\u00e8re que vous allez l\u2019appr\u00e9cier. N\u2019oubliez pas de suivre mon blog, et de partager l\u2019article avec vos proches et amis. Durant ces derni\u00e8res ann\u00e9es, le monde s\u2019est transform\u00e9 en&hellip;","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/1381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/comments?post=1381"}],"version-history":[{"count":5,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/1381\/revisions"}],"predecessor-version":[{"id":2854,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/1381\/revisions\/2854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/media\/2604"}],"wp:attachment":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/media?parent=1381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/categories?post=1381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/tags?post=1381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}