{"id":2422,"date":"2023-01-27T16:59:42","date_gmt":"2023-01-27T16:59:42","guid":{"rendered":"https:\/\/karoslittlecorner.com\/?p=2422"},"modified":"2023-06-09T15:10:48","modified_gmt":"2023-06-09T19:10:48","slug":"trouver-sa-vocation","status":"publish","type":"post","link":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/","title":{"rendered":"Trouver sa vocation"},"content":{"rendered":"<p class=\"has-text-align-center\" style=\"text-align: center;\"><em><strong>Bonjour \u00e0 tous et bonne ann\u00e9e 2023 !! Que cette nouvelle ann\u00e9e vous soit fructueuse! Je suis de retour cette ann\u00e9e avec de bonnes nouvelles. Je vais commencer cet article en les partageant avec vous. Ensuite, je parlerai de vocation et de talents.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Je ne sais pas si vous l\u2019avez remarqu\u00e9, <strong><em>Karo\u2019s little corner<\/em><\/strong> a maintenant son propre domaine. Le blog n\u2019est plus karoslittlecorner.worpress.com mais <a href=\"http:\/\/www.karoslittlecorner.com\">karoslittlecorner.com<\/a>, ce qui est un grand pas pour moi en tant que Blogueuse. Deuxi\u00e8mement, un peu plus bas vous verrez mon nouveau logo. Je voulais quelque chose de simple, qui ait beaucoup de sens et qui me repr\u00e9sente aussi.<\/p>\n<p>Dans ce logo, il y a 4 \u00e9l\u00e9ments : un tournesol, une belle \u00e9criture (style calligraphie) et un stylo avec le symbole infini (\u00e0 moiti\u00e9) en dessous.<\/p>\n<p style=\"text-align: justify;\"><strong>Tournesol<\/strong> : Cette fleur repr\u00e9sente ma marque. Ma m\u00e8re m\u2019a fait r\u00e9aliser que beaucoup de gens reconnaissaient ma page Web par l\u2019image des tournesols (fleur soleil) que j\u2019avais dans mon th\u00e8me pr\u00e9c\u00e9dent. Les tournesols sont un signe de joie et de positivit\u00e9. Je suis quelqu\u2019un qui est toujours joyeuse et qui rayonne de bonheur partout o\u00f9 elle va. Il n\u2019y aurait donc pas de symbole plus pr\u00e9cis que celui-ci ;<\/p>\n<p style=\"text-align: justify;\"><strong>L\u2019\u00e9criture manuscrite et le stylo :\u00a0<\/strong> J\u2019adore \u00e9crire et mes proches savent qu\u2019il ne faut pas laisser un stylo entre mes mains (rires). J\u2019\u00e9crirai sur tout et partout. On m\u2019a \u00e9galement dit \u00e0 plusieurs reprises que j\u2019avais aussi une belle \u00e9criture, alors\u2026 ;<\/p>\n<p style=\"text-align: justify;\"><strong>Le symbole infini : <\/strong>\u00a0Il repr\u00e9sente les innombrables id\u00e9es que j\u2019ai en t\u00eate lorsque j\u2019\u00e9cris sur le blog.\u00a0Mon cerveau n\u2019a pas de limites et comme l\u2019a dit Sukant Ratnakar \u201d\u00a0<em>Notre cerveau est la seule chose dans l\u2019univers qui peut fonctionner dans des dimensions infinies<\/em> \u201c.<\/p>\n<p style=\"text-align: justify;\">Enfin, le design du blog a \u00e9galement chang\u00e9 (c\u2019est un travail encore en cours) et le blog est maintenant disponible en 6 langues diff\u00e9rentes, cliquez simplement sur votre pr\u00e9f\u00e9r\u00e9e. Passons maintenant \u00e0 l\u2019article d\u2019aujourd\u2019hui.<\/p>\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2153\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/Karos-little-corner-Logo.png?resize=642%2C642&ssl=1\" sizes=\"(max-width: 642px) 100vw, 642px\" srcset=\"https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/Karos-little-corner-Logo.png 500w, https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/Karos-little-corner-Logo-300x300.png 300w, https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/Karos-little-corner-Logo-150x150.png 150w, https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/Karos-little-corner-Logo-270x270.png 270w\" alt=\"\" width=\"642\" height=\"642\" \/><\/figure>\n<p style=\"text-align: justify;\">R\u00e9cemment, je naviguais sur Pinterest, et je suis tomb\u00e9e sur une image. C\u2019\u00e9tait un dessin et il a tout de suite attir\u00e9 mon attention. Je ne suis pas une artiste (je ne fais ni dessin ni peinture), mais j\u2019ai toujours voulu en \u00eatre une. J\u2019avais l\u2019habitude d\u2019essayer de faire des portraits mais je n\u2019\u00e9tais jamais satisfaite de mes dessins et j\u2019arrivais toujours \u00e0 la conclusion que ce n\u2019\u00e9tait pas mon talent. Mais ce jour-l\u00e0, j\u2019ai d\u00e9cid\u00e9 d\u2019essayer de recr\u00e9er le dessin. En moins d\u2019une heure, je l\u2019ai termin\u00e9 et j\u2019\u00e9tais impressionn\u00e9e par les r\u00e9sultats. Cela m\u2019a fait r\u00e9aliser \u00e0 quel point j\u2019avais red\u00e9couvert un talent cach\u00e9\/perdu et que je pouvais r\u00e9ellement devenir artiste un jour si je le voulais. Ci-dessous, l\u2019inspiration (de Pinterest, je ne sais pas qui est l\u2019artiste) et ma version.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-2160 size-large aligncenter\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/Sans-titre.png?resize=640%2C512&ssl=1\" sizes=\"(max-width: 640px) 100vw, 640px\" srcset=\"https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/Sans-titre-700x560.png 700w, https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/Sans-titre-300x240.png 300w, https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/Sans-titre-768x614.png 768w, https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/Sans-titre-1536x1229.png 1536w, https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/Sans-titre-338x270.png 338w, https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/Sans-titre-1320x1056.png 1320w, https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/Sans-titre.png 2000w\" alt=\"\" width=\"640\" height=\"512\" \/><\/p>\n<p style=\"text-align: justify;\">Je me souviens qu\u2019au secondaire, j\u2019avais une amie dans mon groupe qui se plaignait toujours du fait que nous avions toutes au moins un talent, et qu\u2019elle n\u2019en avait pas. Je me demandais s\u2019il \u00e9tait possible pour quelqu\u2019un de vivre sans talents. Mais quand je pense \u00e0 la fa\u00e7on dont dans la Bible on parle beaucoup de talents et de dons, j\u2019en suis venue \u00e0 la conclusion que nous avons tous un ou plusieurs talents cach\u00e9s en nous qui n\u2019attendent qu\u2019\u00e0 \u00eatre d\u00e9couverts. \u201d <em>Dans sa gr\u00e2ce, Dieu nous a donn\u00e9 diff\u00e9rents dons pour bien faire certaines choses<\/em>\u00a0\u201d\u00a0<b>Rm 12:6<\/b>\u00a0.\u00a0Je crois que les talents ne se r\u00e9v\u00e8lent pas comme par magie, mais nous devons les rechercher dans notre vie de tous les jours.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-2425 size-full\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/73521.png?resize=604%2C396&ssl=1\" alt=\"\" width=\"604\" height=\"396\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/73521.png?w=604&ssl=1 604w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/73521.png?resize=300%2C197&ssl=1 300w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/73521.png?resize=412%2C270&ssl=1 412w\" sizes=\"(max-width: 604px) 100vw, 604px\" \/><\/p>\n<p style=\"text-align: justify;\">Certaines personnes voient souvent les talents comme la capacit\u00e9 de savoir chanter, danser, dessiner, jouer un instrument\u2026 Selon moi, \u00eatre talentueux signifie plus que cela. Il y a tellement de variations de talents que nous ne connaissons m\u00eame pas. Je me souviens d\u2019avoir vu un homme faire un portrait de Kobe Bryant avec des Rubik\u2019s cubes . En regardant la vid\u00e9o, j\u2019\u00e9tais hypnotis\u00e9e et je ne pouvais pas m\u2019emp\u00eacher de me demander comment quelqu\u2019un avait d\u00e9couvert qu\u2019il avait ce talent. Est-ce qu\u2019il s\u2019est r\u00e9veill\u00e9 un jour et s\u2019est dit \u00ab Laisse-moi faire de l\u2019art en utilisant le Rubik\u2019s cube \u00bb et a r\u00e9ussi ? Cela m\u2019a fait r\u00e9aliser que la quantit\u00e9 de variation de talents qui existe dans le monde est incommensurable. Certains talents sont encore \u00e0 d\u00e9couvrir. Ils ont juste besoin de cette personne pr\u00eate \u00e0 essayer afin de montrer la voie aux autres.<\/p>\n<p style=\"text-align: justify;\">De nos jours, la technologie et surtout l\u2019internet nous poussent \u00e0 \u00eatre plus cr\u00e9atifs, en particulier les plus jeunes. Lorsqu\u2019on regarde certaines des pages des influenceurs et des cr\u00e9ateurs de contenu, on peut constater \u00e0 quel point ils peuvent cr\u00e9er du beau \u00e0 partir de n\u2019importe quoi. Pour moi, c\u2019est un sacr\u00e9 talent. Si, comme mon amie, vous avez l\u2019impression d\u2019\u00eatre n\u00e9 sans talents, je partagerai ci-dessous quelques conseils pour vous aider \u00e0 d\u00e9couvrir vos talents cach\u00e9s et trouver votre passion.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2427 size-full\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/citation-de-gustave-flaubert-ecdc232ecab65592.jpeg?resize=422%2C281&ssl=1\" alt=\"\" width=\"422\" height=\"281\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/citation-de-gustave-flaubert-ecdc232ecab65592.jpeg?w=422&ssl=1 422w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/citation-de-gustave-flaubert-ecdc232ecab65592.jpeg?resize=300%2C200&ssl=1 300w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/citation-de-gustave-flaubert-ecdc232ecab65592.jpeg?resize=405%2C270&ssl=1 405w\" sizes=\"(max-width: 422px) 100vw, 422px\" \/><\/p>\n<p style=\"text-align: justify;\"><em><strong>\u2013 Croyez en vous. <\/strong><\/em>Personne ne peut rien accomplir dans cette vie si elle ne croit pas en ses capacit\u00e9s. La confiance en soi vous conduira \u00e0 votre motivation. C\u2019est ce qui va vous pousser \u00e0 essayer encore et encore jusqu\u2019\u00e0 ce que vous atteigniez votre objectif.<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u2013 Identifiez une chose dans laquelle vous excellez. <\/strong><\/em>Qu\u2019est-ce vous aimez faire, qu\u2019est-ce qui vous procure du plaisir ? Comment vous sentez-vous lorsque vous faites cette chose sp\u00e9cifique ? Avez-vous l\u2019impression que c\u2019est quelque chose que vous faites mieux que la plupart des gens\u00a0?<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u2013 Demandez aux gens autour de vous.\u00a0<\/strong><\/em>Parfois, nous ne r\u00e9alisons pas le don que nous avons, mais les gens autour de nous oui. Demandez \u00e0 vos proches quelle est la chose pour laquelle ils pensent que vous \u00eates dou\u00e9, les choses que vous faites sans effort ou tout simplement ce que vous faites mieux que la plupart des gens. Cela vous permettra de savoir o\u00f9 vous pouvez puiser votre talent. Utilisez leur point de vue et examinez les qualit\u00e9s identifi\u00e9es. Votre famille peut \u00e9galement \u00eatre une bonne source d\u2019informations. Vos parents ainsi que vos fr\u00e8res et s\u0153urs savent ce que vous aimiez faire dans votre enfance et que vous avez probablement cess\u00e9 de faire avec le temps. Cela peut vous aider \u00e0 d\u00e9couvrir un talent perdu depuis longtemps.<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u2013 Sortez de votre zone de confort.\u00a0<\/strong>\u00a0<\/em>Lorsque vous \u00eates dans votre zone de confort, vous ne voulez faire que des choses qui vous sont famili\u00e8res, vous ne vous engagez dans rien de nouveau et cela peut vous faire rater de belles opportunit\u00e9s pour d\u00e9couvrir vos talents. Essayez de nouvelles choses, \u00e9largissez vos horizons, ne vous limitez pas !<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u2013 Exp\u00e9rimentez des talents que vous aimeriez avoir. <\/strong><\/em>Comme je l\u2019ai dit au d\u00e9but, j\u2019ai toujours voulu dessiner. Je pensais que je ne pourrais jamais le faire, parce que dans ma t\u00eate je n\u2019\u00e9tais pas assez dou\u00e9e mais j\u2019ai quand m\u00eame essay\u00e9. S\u2019il y a quelque chose que vous avez toujours voulu faire, essayez maintenant, de toute fa\u00e7on vous n\u2019avez rien \u00e0 perdre. De plus, de nos jours, avec l\u2019aide de YouTube et Pinterest, nous pouvons essentiellement apprendre tout ce que nous voulons gratuitement, tant que nous avons notre mat\u00e9riel.<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2428 size-full\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/596878e74422c83001c500654196d4c5.jpg?resize=612%2C612&ssl=1\" alt=\"\" width=\"612\" height=\"612\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/596878e74422c83001c500654196d4c5.jpg?w=612&ssl=1 612w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/596878e74422c83001c500654196d4c5.jpg?resize=300%2C300&ssl=1 300w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/596878e74422c83001c500654196d4c5.jpg?resize=150%2C150&ssl=1 150w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/596878e74422c83001c500654196d4c5.jpg?resize=270%2C270&ssl=1 270w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/p>\n<p style=\"text-align: justify;\"><em><strong>\u2013 Puisez votre talent chez les autres.<\/strong>\u201c<a href=\"https:\/\/www.linkedin.com\/pulse\/10-ways-identify-your-talents-utilize-them-laila-ali-khan\"> Puiser le talent chez les autres vous ouvrira des opportunit\u00e9s et des connexions tout en vous aidant \u00e0 d\u00e9finir le v\u00f4tre<\/a> .\u201d\u00a0Laila Ali Khan.\u00a0<\/em>Parfois, tout ce dont nous avons besoin, c\u2019est un peu d\u2019inspiration. Regardez autour de vous, que font vos amis ? Quels sont leurs talents ? Y en a-t-il un en particulier qui a retenu votre attention ? Lequel ? Si vous voyez quelque chose qui retient votre attention, utilisez-la \u00e0 votre avantage. Demandez \u00e0 cet ami de vous aider et si \u00e7a ne marche pas pour vous, continuer \u00e0 chercher mais n\u2019abandonnez jamais.<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u2013 Faites un quiz de personnalit\u00e9 ou de carri\u00e8re. <\/strong><\/em>Ce genre de quizz peut parfois vous guider dans la bonne direction. Il existe des milliers de tests de personnalit\u00e9 gratuits en ligne qui vous aidront \u00e0 d\u00e9couvrir vos points forts et comment vous pouvez les transformer en talents.<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u2013 Identifiez vos succ\u00e8s ant\u00e9rieurs. <\/strong><\/em>Avez-vous d\u00e9j\u00e0 re\u00e7u un prix ou tout autre type de reconnaissance pour quelque chose que vous avez faite ? Personnellement c\u2019est ainsi que j\u2019ai d\u00e9couvert ma vocation pour le blogging (l\u2019\u00e9criture en g\u00e9n\u00e9ral). Quand j\u2019\u00e9tais en classe de Rh\u00e9to, ma directrice de l\u2019\u00e9poque, Sr Jeanine (qu\u2019elle repose en paix!), a d\u00e9cid\u00e9 de m\u2019inscrire \u00e0 un concours d\u2019Ecriture pour repr\u00e9senter mon \u00e9cole. Je n\u2019avais aucune exp\u00e9rience d\u2019\u00e9criture et je n\u2019avais aucune id\u00e9e de la raison pour laquelle elle m\u2019avait choisie. J\u2019ai eu quelques jours pour soumettre le texte, et laissez-moi vous dire que la pression \u00e9tait forte. C\u2019\u00e9tait un concours national et plusieurs \u00e9coles du pays y participaient \u00e9galement. Je me souviens combien j\u2019ai pleur\u00e9 quand j\u2019essayais d\u2019\u00e9crire ce texte. Je suis rest\u00e9e \u00e9veill\u00e9e toute la nuit avec mon fr\u00e8re et je n\u2019arr\u00eatais pas de me plaindre du fait que j\u2019\u00e9tais celle qu\u2019on avait choisie. En fin de compte, j\u2019ai gagn\u00e9 ce concours et mon po\u00e8me \u00e9tait le meilleur du pays. Ce succ\u00e8s est l\u2019une des raisons pour lesquelles je suis blogueuse aujourd\u2019hui. Cela pourrait aussi \u00eatre votre cas.<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u2013 Prenez des notes sur ce pour quoi les gens vous complimentent habituellement.\u00a0<\/strong><\/em>Il y a des choses que nous faisons que les gens appr\u00e9cient vraiment et pour lesquelles ils nous complimentent. Par exemple, je re\u00e7ois beaucoup de compliments quand je fais de la p\u00e2tisserie, que ce soit des g\u00e2teaux, des cupcakes etc\u2026 Je n\u2019ai jamais suivi de cours de cuisine\/p\u00e2tisserie. Je fais presque tout de mani\u00e8re naturelle. Ces compliments m\u2019ont fait r\u00e9aliser que j\u2019ai un don, et c\u2019est pourquoi maintenant, je m\u2019entra\u00eene davantage et travaille pour \u00eatre meilleure chaque jour afin d\u2019utiliser ce talent \u00e0 mon avantage et au service des autres.<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u2013 Ne restez pas concentr\u00e9 sur les talents tangibles.\u00a0<\/strong><\/em>Comme je l\u2019ai dit au d\u00e9but, quand on parle de talents, on se concentre surtout sur des choses qu\u2019on peut montrer aux autres, des choses qui sont tangibles. Certaines personnes ont des dons qui ne sont pas tangibles. J\u2019ai une amie, elle est vraiment dou\u00e9e pour donner des conseils, peu importe la situation, peu importe ce que vous traversez, c\u2019est la personne qui sait toujours quoi dire. Pour moi, c\u2019est un talent. Elle n\u2019est pas psy, ce n\u2019est pas quelque chose qu\u2019elle a \u00e9tudi\u00e9e mais elle est vraiment dou\u00e9e pour \u00e7a. Regardez plus en profondeur, le talent n\u2019est pas toujours ce qui est \u00e0 la surface. Vous ne savez peut-\u00eatre pas peindre, chanter, jouer \u00e0 un instrument, mais vous pouvez faire d\u2019autres choses incroyables.<\/p>\n<p style=\"text-align: justify;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2426 size-full\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/06072018-talents-besoins-monde-aristote-665x446-1.png?resize=665%2C446&ssl=1\" alt=\"\" width=\"665\" height=\"446\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/06072018-talents-besoins-monde-aristote-665x446-1.png?w=665&ssl=1 665w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/06072018-talents-besoins-monde-aristote-665x446-1.png?resize=300%2C201&ssl=1 300w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/06072018-talents-besoins-monde-aristote-665x446-1.png?resize=403%2C270&ssl=1 403w\" sizes=\"(max-width: 665px) 100vw, 665px\" \/>Maintenant que vous avez identifi\u00e9 votre talent, vous ne pouvez plus le garder pour vous. Les talents sont faits pour \u00eatre montr\u00e9s et utilis\u00e9s. Si je recevais un dollar \u00e0 chaque fois que quelqu\u2019un m\u2019encourageait \u00e0 montrer mes talents au monde, je serais riche maintenant. Ma m\u00e8re en est le plus grand exemple. Elle nous encourage toujours, mon fr\u00e8re et moi, \u00e0 enregistrer des vid\u00e9os, en train de jouer \u00e0 la guitare afin de publier sur YouTube. Elle m\u2019encourage \u00e9galement \u00e0 \u00e9crire et \u00e0 publier mon premier livre. Nous avons tous besoin de quelqu\u2019un comme elle dans nos vies. Quelqu\u2019un pour nous pousser hors de notre zone de confort, quelqu\u2019un qui croit en nous et qui est toujours l\u00e0 pour nous soutenir. Vous trouverez votre vocation en combinant votre talent et votre volont\u00e9 pour \u00eatre meilleur chaque jour.<\/p>\n<p style=\"text-align: justify;\">Avant de terminer, je tiens \u00e0 remercier chaleureusement certaines personnes qui ont fait de cette transition un succ\u00e8s. D\u2019abord mon fr\u00e8re Gerry, puis mon ami Jonathan qui m\u2019a donn\u00e9 l\u2019id\u00e9e d\u2019avoir mon propre domaine et qui a aussi fait la migration du blog afin que je ne perde pas mes articles pr\u00e9c\u00e9dents et enfin mon amie Audrey qui m\u2019a aid\u00e9e \u00e0 concevoir mon logo. Dieu sait combien je les ai fait souffrir ces derni\u00e8res semaines avec mes textos et mes appels. Je ne sais vraiment pas comment les remercier !<\/p>\n<p style=\"text-align: center;\"><em><strong>C\u2019est tout pour aujourd\u2019hui . J\u2019esp\u00e8re que ce premier article pour la nouvelle ann\u00e9e sera le coup de pouce dont vous avez besoin pour commencer \u00e0 utiliser\/rechercher votre talent. C\u2019est votre ann\u00e9e, faites-en la meilleure de votre vie ! J\u2019esp\u00e8re que vous avez pris autant de plaisir \u00e0 lire cet article que j\u2019en ai eu \u00e0 l\u2019\u00e9crire. S\u2019il vous pla\u00eet, supporez-moi en partageant mon Blog avec vos amis et aidez-moi \u00e0 grandir mon audience. En attendant la prochaine publication, restez en s\u00e9curit\u00e9 et soyez b\u00e9nis\u2026 toujours !<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour \u00e0 tous et bonne ann\u00e9e 2023 !! Que cette nouvelle ann\u00e9e vous soit fructueuse! Je suis de retour cette ann\u00e9e avec de bonnes nouvelles. Je vais commencer cet article en les partageant avec vous. Ensuite, je parlerai de vocation et de talents. Je ne sais pas si vous l\u2019avez remarqu\u00e9, Karo\u2019s little corner a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":{"0":"post-2422","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-traduction-francaise"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trouver sa vocation -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trouver sa vocation -\" \/>\n<meta property=\"og:description\" content=\"Bonjour \u00e0 tous et bonne ann\u00e9e 2023 !! Que cette nouvelle ann\u00e9e vous soit fructueuse! Je suis de retour cette ann\u00e9e avec de bonnes nouvelles. Je vais commencer cet article en les partageant avec vous. Ensuite, je parlerai de vocation et de talents. Je ne sais pas si vous l\u2019avez remarqu\u00e9, Karo\u2019s little corner a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-27T16:59:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-09T19:10:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"karoaug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"karoaug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/01\\\/27\\\/trouver-sa-vocation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/01\\\/27\\\/trouver-sa-vocation\\\/\"},\"author\":{\"name\":\"karoaug\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"headline\":\"Trouver sa vocation\",\"datePublished\":\"2023-01-27T16:59:42+00:00\",\"dateModified\":\"2023-06-09T19:10:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/01\\\/27\\\/trouver-sa-vocation\\\/\"},\"wordCount\":2138,\"commentCount\":9,\"publisher\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"image\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/01\\\/27\\\/trouver-sa-vocation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/pexels-tobi-631986-scaled.webp?fit=2560%2C1704&ssl=1\",\"articleSection\":[\"Traduction fran\u00e7aise\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/01\\\/27\\\/trouver-sa-vocation\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/01\\\/27\\\/trouver-sa-vocation\\\/\",\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/01\\\/27\\\/trouver-sa-vocation\\\/\",\"name\":\"Trouver sa vocation -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/01\\\/27\\\/trouver-sa-vocation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/01\\\/27\\\/trouver-sa-vocation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/pexels-tobi-631986-scaled.webp?fit=2560%2C1704&ssl=1\",\"datePublished\":\"2023-01-27T16:59:42+00:00\",\"dateModified\":\"2023-06-09T19:10:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/01\\\/27\\\/trouver-sa-vocation\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/01\\\/27\\\/trouver-sa-vocation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/01\\\/27\\\/trouver-sa-vocation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/pexels-tobi-631986-scaled.webp?fit=2560%2C1704&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/pexels-tobi-631986-scaled.webp?fit=2560%2C1704&ssl=1\",\"width\":2560,\"height\":1704},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/01\\\/27\\\/trouver-sa-vocation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/karoslittlecorner.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trouver sa vocation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#website\",\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/\",\"name\":\"karoslittlecorner\",\"description\":\"Karo&#039;s blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/karoslittlecorner.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\",\"name\":\"karoaug\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"karoaug\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\"},\"sameAs\":[\"https:\\\/\\\/karoslittlecorner.com\"],\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/author\\\/karoaug\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trouver sa vocation -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/","og_locale":"en_US","og_type":"article","og_title":"Trouver sa vocation -","og_description":"Bonjour \u00e0 tous et bonne ann\u00e9e 2023 !! Que cette nouvelle ann\u00e9e vous soit fructueuse! Je suis de retour cette ann\u00e9e avec de bonnes nouvelles. Je vais commencer cet article en les partageant avec vous. Ensuite, je parlerai de vocation et de talents. Je ne sais pas si vous l\u2019avez remarqu\u00e9, Karo\u2019s little corner a [&hellip;]","og_url":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/","article_published_time":"2023-01-27T16:59:42+00:00","article_modified_time":"2023-06-09T19:10:48+00:00","og_image":[{"width":2560,"height":1704,"url":"https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp","type":"image\/jpeg"}],"author":"karoaug","twitter_card":"summary_large_image","twitter_misc":{"Written by":"karoaug","Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/#article","isPartOf":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/"},"author":{"name":"karoaug","@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"headline":"Trouver sa vocation","datePublished":"2023-01-27T16:59:42+00:00","dateModified":"2023-06-09T19:10:48+00:00","mainEntityOfPage":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/"},"wordCount":2138,"commentCount":9,"publisher":{"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"image":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?fit=2560%2C1704&ssl=1","articleSection":["Traduction fran\u00e7aise"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/","url":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/","name":"Trouver sa vocation -","isPartOf":{"@id":"https:\/\/karoslittlecorner.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/#primaryimage"},"image":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?fit=2560%2C1704&ssl=1","datePublished":"2023-01-27T16:59:42+00:00","dateModified":"2023-06-09T19:10:48+00:00","breadcrumb":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/#primaryimage","url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?fit=2560%2C1704&ssl=1","contentUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?fit=2560%2C1704&ssl=1","width":2560,"height":1704},{"@type":"BreadcrumbList","@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/01\/27\/trouver-sa-vocation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/karoslittlecorner.com\/"},{"@type":"ListItem","position":2,"name":"Trouver sa vocation"}]},{"@type":"WebSite","@id":"https:\/\/karoslittlecorner.com\/#website","url":"https:\/\/karoslittlecorner.com\/","name":"karoslittlecorner","description":"Karo&#039;s blog","publisher":{"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/karoslittlecorner.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909","name":"karoaug","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"karoaug"},"logo":{"@id":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1"},"sameAs":["https:\/\/karoslittlecorner.com"],"url":"https:\/\/karoslittlecorner.com\/index.php\/author\/karoaug\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?fit=2560%2C1704&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?fit=2560%2C1704&ssl=1",2560,1704,false],"thumbnail":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?fit=768%2C511&ssl=1",768,511,true],"large":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?fit=700%2C466&ssl=1",700,466,true],"1536x1536":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?fit=1536%2C1022&ssl=1",1536,1022,true],"2048x2048":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?fit=2048%2C1363&ssl=1",2048,1363,true],"pixwell_370x250":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?resize=370%2C250&ssl=1",370,250,true],"pixwell_370x250-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?resize=740%2C500&ssl=1",740,500,true],"pixwell_370x250-3x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?resize=1110%2C750&ssl=1",1110,750,true],"pixwell_280x210":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?resize=280%2C210&ssl=1",280,210,true],"pixwell_280x210-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?resize=560%2C420&ssl=1",560,420,true],"pixwell_400x450":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?resize=400%2C450&ssl=1",400,450,true],"pixwell_400x600":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?resize=400%2C600&ssl=1",400,600,true],"pixwell_450x0":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?resize=450%2C299&ssl=1",450,299,true],"pixwell_780x0":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?resize=780%2C519&ssl=1",780,519,true],"pixwell_780x0-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?resize=1600%2C1065&ssl=1",1600,1065,true],"mailpoet_newsletter_max":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/pexels-tobi-631986-scaled.webp?fit=1320%2C878&ssl=1",1320,878,true]},"uagb_author_info":{"display_name":"karoaug","author_link":"https:\/\/karoslittlecorner.com\/index.php\/author\/karoaug\/"},"uagb_comment_info":34,"uagb_excerpt":"Bonjour \u00e0 tous et bonne ann\u00e9e 2023 !! Que cette nouvelle ann\u00e9e vous soit fructueuse! Je suis de retour cette ann\u00e9e avec de bonnes nouvelles. Je vais commencer cet article en les partageant avec vous. Ensuite, je parlerai de vocation et de talents. Je ne sais pas si vous l\u2019avez remarqu\u00e9, Karo\u2019s little corner a&hellip;","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/2422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/comments?post=2422"}],"version-history":[{"count":18,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/2422\/revisions"}],"predecessor-version":[{"id":2847,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/2422\/revisions\/2847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/media\/2595"}],"wp:attachment":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/media?parent=2422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/categories?post=2422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/tags?post=2422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}