{"id":3343,"date":"2023-06-02T17:53:25","date_gmt":"2023-06-02T21:53:25","guid":{"rendered":"https:\/\/karoslittlecorner.com\/?p=3343"},"modified":"2023-06-09T15:01:51","modified_gmt":"2023-06-09T19:01:51","slug":"savoir-fixer-ses-limites","status":"publish","type":"post","link":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/","title":{"rendered":"Savoir fixer ses limites"},"content":{"rendered":"<p style=\"text-align: center;\"><em><strong>Bonjour \u00e0 tous et bienvenue sur mon blog. Le mois de mai est enfin termin\u00e9 et en un clin d\u2019oeil, nous avons atteint la moiti\u00e9 de l\u2019ann\u00e9e. Ce n\u2019est pas croyable. Etes-vous satisfaits de ce que vous avez accompli jusqu\u2019\u00e0 maintenant? Quelle que soit la r\u00e9ponse \u00e0 cette question, je veux que vous sachiez que malgr\u00e9 tout, vous vous en sortez bien, continuez \u00e0 avancer \u2764\ufe0f.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Je viens de voir un post sur Instagram qui parle des raisons pour lesquelles il faut \u201cFixer ses limites (dans les relations interpersonnelles)\u201d, et je veux partager certaines id\u00e9es avec vous. Tout d\u2019abord, comprenons ce que signifie l\u2019expression, selon le contexte.<\/p>\n<p style=\"text-align: justify;\"><strong>Qu\u2019est-ce qu\u2019une limite ?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cUne ligne invisible qui d\u00e9finit les comportements acceptables pour un individu. Les limites peuvent \u00eatre physiques (par exemple, \u201cNe me touche pas\u201d) ou \u00e9motionnelles (\u201cNe me mens pas\u201d)\u201d<a href=\"https:\/\/wellnesscenter.uic.edu\/news-stories\/boundaries-what-are-they-and-how-to-create-them\/\">1<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>Que signifie fixer ses limites ?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cFixer ses limites est une pratique de bien-\u00eatre personnel. Cela permet de cr\u00e9er une ligne directrice, une r\u00e8gle ou des limites claires sur la fa\u00e7on dont vous aimeriez \u00eatre trait\u00e9(e). Ce qui permet aux autres de savoir ce qui est acceptable et ce qui ne l\u2019est pas. Enfin, \u00e7a permet d\u2019honorer nos besoins et nos d\u00e9sirs afin que nous nous sentions respect\u00e9s et en s\u00e9curit\u00e9.\u201d <a href=\"https:\/\/wellnesscenter.uic.edu\/news-stories\/boundaries-what-are-they-and-how-to-create-them\/\">2<\/a><\/p>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-large wp-image-3357\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Make-a-Difference-Vintage-Instagram-Quote-1.png?resize=700%2C700&ssl=1\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Make-a-Difference-Vintage-Instagram-Quote-1.png?resize=700%2C700&ssl=1 700w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Make-a-Difference-Vintage-Instagram-Quote-1.png?resize=300%2C300&ssl=1 300w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Make-a-Difference-Vintage-Instagram-Quote-1.png?resize=150%2C150&ssl=1 150w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Make-a-Difference-Vintage-Instagram-Quote-1.png?resize=768%2C768&ssl=1 768w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Make-a-Difference-Vintage-Instagram-Quote-1.png?resize=450%2C450&ssl=1 450w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Make-a-Difference-Vintage-Instagram-Quote-1.png?resize=780%2C780&ssl=1 780w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Make-a-Difference-Vintage-Instagram-Quote-1.png?w=1080&ssl=1 1080w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p style=\"text-align: center;\"><strong>Voici six fa\u00e7ons diff\u00e9rentes de fixer des limites, tout en restant poli :<\/strong><\/p>\n<p style=\"text-align: justify;\"><em><strong>1. D\u00e9finissez vos limites et communiquez-les.<\/strong><\/em> Pour savoir si quelqu\u2019un franchit vos limites, vous devez en avoir. Si vous ne savez pas ce qui vous d\u00e9range et ce que vous consid\u00e9rez comme un manque de respect, comment voulez-vous que quelqu\u2019un d\u2019autre respecte vos limites et ne vous marche pas dessus ? Vous devez les d\u00e9finir clairement et exprimer de mani\u00e8re vocale ce que vous n\u2019aimez pas et ce que vous consid\u00e9rez comme inappropri\u00e9. Ne vous contentez pas de fixer des limites mentalement et ne vous attendez pas \u00e0 ce que les autres devinent ce qui vous d\u00e9range.<\/p>\n<blockquote>\n<p style=\"text-align: center;\">Oser se fixer des limites, c\u2019est avoir le courage de nous aimer nous-m\u00eames, m\u00eame si nous risquons de d\u00e9cevoir les autres.<strong> <em>Brene Brown<\/em><\/strong><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><em><strong>2. Ne jamais supposer ou deviner les sentiments de quelqu\u2019un d\u2019autre.<\/strong> <\/em>Vous ne pouvez pas supposer que les gens savent n\u00e9cessairement quand ils d\u00e9passent les bornes. Certaines personnes r\u00e9agissent d\u2019une certaine mani\u00e8re, tout simplement parce que pour elles, leur comportement est normal. Elles le font \u00e0 d\u2019autres et n\u2019ont jamais \u00e9t\u00e9 r\u00e9primand\u00e9. C\u2019est pourquoi il est important de communiquer ouvertement et clairement vos limites afin d\u2019\u00e9viter tout malentendu.<\/p>\n<p style=\"text-align: justify;\"><em><strong>3. Apprenez \u00e0 dire non.<\/strong><\/em> Beaucoup d\u2019entre nous ont du mal \u00e0 le faire, moi en premier. Nous pensons souvent que le fait de dire non est un signe d\u2019impolitesse. C\u2019est l\u2019un des sympt\u00f4mes courants des gens qui ont un caract\u00e8re de \u201cpeople-pleaser\u201d (qui fait tout pour plaire aux gens), mais cela peut aussi \u00eatre simplement d\u00fb au fait que nous ayons horreur des conflits. Nous faisons passer les sentiments des autres avant les n\u00f4tres, et c\u2019est toujours nous qui finissons par \u00eatre bless\u00e9s. Le fait de dire non est l\u2019\u00e9tape la plus importante lorsqu\u2019il s\u2019agit de fixer des limites. Apprenez \u00e0 dire non et accepter que quelqu\u2019un d\u2019autre vous le dise aussi.<\/p>\n<p style=\"text-align: justify;\"><em><strong>4. Soyez ferme dans votre d\u00e9cision.<\/strong><\/em> Une fois que vous avez pris une d\u00e9cision, vous ne devez pas vous laisser influencer par l\u2019id\u00e9e de revenir l\u00e0-dessus. M\u00eame si vous vous sentez mal par la suite, il faut garder \u00e0 l\u2019esprit que c\u2019est pour une bonne cause. Le fait de laisser passer certaines choses, cr\u00e9\u00e9 de la confusion et encourage aussi les gens \u00e0 continuer d\u2019outrepasser leurs droits. Soyez coh\u00e9rent, une fois que vous avez dit non, il n\u2019y a pas de retour possible.<\/p>\n<p style=\"text-align: justify;\"><em><strong>5. Pr\u00e9parez-vous \u00e0 ce qui va suivre.<\/strong><\/em> Lorsque vous fixez des limites, vous devez \u00eatre suffisamment fort pour accepter que cela ne plaira pas \u00e0 tout le monde. Les gens vont se sentir offens\u00e9s parce qu\u2019ils n\u2019ont plus \u201clibre acc\u00e8s\u201d \u00e0 vous. Vous avez des droits, vous avez le droit de d\u00e9finir ce qui est juste et ce qui ne l\u2019est pas. Vous devez accepter que vos sentiments comptent plus que ceux des autres. Comme le dit le proverbe : \u201c<em>On n\u2019est pas oblig\u00e9 de s\u2019immoler par le feu pour tenir les autres au chaud<\/em>\u201c. Toute personne qui ne peut pas accepter et respecter vos limites n\u2019a pas sa place dans votre vie.<img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter size-large wp-image-3358\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Beige-Modern-Hello-Spring-Instagram-Post-1.png?resize=700%2C700&ssl=1\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Beige-Modern-Hello-Spring-Instagram-Post-1.png?resize=700%2C700&ssl=1 700w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Beige-Modern-Hello-Spring-Instagram-Post-1.png?resize=300%2C300&ssl=1 300w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Beige-Modern-Hello-Spring-Instagram-Post-1.png?resize=150%2C150&ssl=1 150w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Beige-Modern-Hello-Spring-Instagram-Post-1.png?resize=768%2C768&ssl=1 768w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Beige-Modern-Hello-Spring-Instagram-Post-1.png?resize=450%2C450&ssl=1 450w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Beige-Modern-Hello-Spring-Instagram-Post-1.png?resize=780%2C780&ssl=1 780w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Beige-Modern-Hello-Spring-Instagram-Post-1.png?w=1080&ssl=1 1080w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p style=\"text-align: justify;\"><em><strong>6. N\u2019attendez pas le \u201cbon\u201d moment.<\/strong> <\/em>Lorsque vous avez l\u2019impression qu\u2019on ne vous respecte pas, vous devez agir sur le moment et vous exprimer. Parfois, nous ne r\u00e9alisons pas le poids des mots sur le tas, il nous faut du temps pour r\u00e9fl\u00e9chir et tirer une conclusion; \u00e7a m\u2019arrive souvent. Mais d\u00e8s que vous vous en rendez compte, vous devez en parler. Plus vous attendez, plus vos paroles n\u2019auront pas de valeur. C\u2019est pourquoi il est tr\u00e8s important de s\u2019exprimer le plus t\u00f4t possible, lorsque les limites sont franchies.<\/p>\n<p style=\"text-align: justify;\">Enfin, nous devons comprendre que des relations diff\u00e9rentes exigent des limites diff\u00e9rentes, ce qui peut \u00eatre accept\u00e9 pour un groupe de personnes peut ne pas l\u2019\u00eatre pour un autre groupe. Il faut toujours r\u00e9agir avec calme et respect. Ce n\u2019est pas en \u00e9levant la voix que l\u2019on se fera entendre. Parfois, les gens ont besoin d\u2019\u00eatre guid\u00e9s, afin de savoir comment mieux vous traiter, donnez-leur un coup de main en fixant vos limites. Fixer des limites n\u2019est pas une t\u00e2che facile, \u00e7a prendra du temps, alors soyez patient et entra\u00eenez-vous. Au final, c\u2019est un exercice qui ne peut \u00eatre que b\u00e9n\u00e9fique pour nous.<img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter size-large wp-image-3359\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Benefits-of-setting-boundaries-700x700.webp?resize=700%2C700&ssl=1\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Benefits-of-setting-boundaries-jpg.webp?resize=700%2C700&ssl=1 700w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Benefits-of-setting-boundaries-jpg.webp?resize=300%2C300&ssl=1 300w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Benefits-of-setting-boundaries-jpg.webp?resize=150%2C150&ssl=1 150w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Benefits-of-setting-boundaries-jpg.webp?resize=768%2C768&ssl=1 768w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Benefits-of-setting-boundaries-jpg.webp?resize=450%2C450&ssl=1 450w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Benefits-of-setting-boundaries-jpg.webp?resize=780%2C780&ssl=1 780w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/Benefits-of-setting-boundaries-jpg.webp?w=1080&ssl=1 1080w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p style=\"text-align: center;\"><em><strong>C\u2019est tout pour aujourd\u2019hui. J\u2019esp\u00e8re que vous avez pris autant de plaisir \u00e0 lire cet article que j\u2019en ai eu \u00e0 l\u2019\u00e9crire. En attendant la prochaine publication, restez prudents et soyez b\u00e9nis\u2026 toujours !<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour \u00e0 tous et bienvenue sur mon blog. Le mois de mai est enfin termin\u00e9 et en un clin d\u2019oeil, nous avons atteint la moiti\u00e9 de l\u2019ann\u00e9e. Ce n\u2019est pas croyable. Etes-vous satisfaits de ce que vous avez accompli jusqu\u2019\u00e0 maintenant? Quelle que soit la r\u00e9ponse \u00e0 cette question, je veux que vous sachiez que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3311,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":{"0":"post-3343","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-traduction-francaise"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Savoir fixer ses limites -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Savoir fixer ses limites -\" \/>\n<meta property=\"og:description\" content=\"Bonjour \u00e0 tous et bienvenue sur mon blog. Le mois de mai est enfin termin\u00e9 et en un clin d\u2019oeil, nous avons atteint la moiti\u00e9 de l\u2019ann\u00e9e. Ce n\u2019est pas croyable. Etes-vous satisfaits de ce que vous avez accompli jusqu\u2019\u00e0 maintenant? Quelle que soit la r\u00e9ponse \u00e0 cette question, je veux que vous sachiez que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-02T21:53:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-09T19:01:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=2560%2C1707&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"karoaug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"karoaug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/06\\\/02\\\/savoir-fixer-ses-limites\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/06\\\/02\\\/savoir-fixer-ses-limites\\\/\"},\"author\":{\"name\":\"karoaug\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"headline\":\"Savoir fixer ses limites\",\"datePublished\":\"2023-06-02T21:53:25+00:00\",\"dateModified\":\"2023-06-09T19:01:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/06\\\/02\\\/savoir-fixer-ses-limites\\\/\"},\"wordCount\":987,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"image\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/06\\\/02\\\/savoir-fixer-ses-limites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=2560%2C1707&ssl=1\",\"articleSection\":[\"Traduction fran\u00e7aise\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/06\\\/02\\\/savoir-fixer-ses-limites\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/06\\\/02\\\/savoir-fixer-ses-limites\\\/\",\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/06\\\/02\\\/savoir-fixer-ses-limites\\\/\",\"name\":\"Savoir fixer ses limites -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/06\\\/02\\\/savoir-fixer-ses-limites\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/06\\\/02\\\/savoir-fixer-ses-limites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=2560%2C1707&ssl=1\",\"datePublished\":\"2023-06-02T21:53:25+00:00\",\"dateModified\":\"2023-06-09T19:01:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/06\\\/02\\\/savoir-fixer-ses-limites\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/06\\\/02\\\/savoir-fixer-ses-limites\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/06\\\/02\\\/savoir-fixer-ses-limites\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=2560%2C1707&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=2560%2C1707&ssl=1\",\"width\":2560,\"height\":1707,\"caption\":\"Picture from Pexels.com\\\/nataliya\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2023\\\/06\\\/02\\\/savoir-fixer-ses-limites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/karoslittlecorner.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Savoir fixer ses limites\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#website\",\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/\",\"name\":\"karoslittlecorner\",\"description\":\"Karo&#039;s blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/karoslittlecorner.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\",\"name\":\"karoaug\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"karoaug\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\"},\"sameAs\":[\"https:\\\/\\\/karoslittlecorner.com\"],\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/author\\\/karoaug\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Savoir fixer ses limites -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/","og_locale":"en_US","og_type":"article","og_title":"Savoir fixer ses limites -","og_description":"Bonjour \u00e0 tous et bienvenue sur mon blog. Le mois de mai est enfin termin\u00e9 et en un clin d\u2019oeil, nous avons atteint la moiti\u00e9 de l\u2019ann\u00e9e. Ce n\u2019est pas croyable. Etes-vous satisfaits de ce que vous avez accompli jusqu\u2019\u00e0 maintenant? Quelle que soit la r\u00e9ponse \u00e0 cette question, je veux que vous sachiez que [&hellip;]","og_url":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/","article_published_time":"2023-06-02T21:53:25+00:00","article_modified_time":"2023-06-09T19:01:51+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=2560%2C1707&ssl=1","type":"image\/jpeg"}],"author":"karoaug","twitter_card":"summary_large_image","twitter_misc":{"Written by":"karoaug","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/#article","isPartOf":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/"},"author":{"name":"karoaug","@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"headline":"Savoir fixer ses limites","datePublished":"2023-06-02T21:53:25+00:00","dateModified":"2023-06-09T19:01:51+00:00","mainEntityOfPage":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/"},"wordCount":987,"commentCount":0,"publisher":{"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"image":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=2560%2C1707&ssl=1","articleSection":["Traduction fran\u00e7aise"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/","url":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/","name":"Savoir fixer ses limites -","isPartOf":{"@id":"https:\/\/karoslittlecorner.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/#primaryimage"},"image":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=2560%2C1707&ssl=1","datePublished":"2023-06-02T21:53:25+00:00","dateModified":"2023-06-09T19:01:51+00:00","breadcrumb":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/#primaryimage","url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=2560%2C1707&ssl=1","contentUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=2560%2C1707&ssl=1","width":2560,"height":1707,"caption":"Picture from Pexels.com\/nataliya"},{"@type":"BreadcrumbList","@id":"https:\/\/karoslittlecorner.com\/index.php\/2023\/06\/02\/savoir-fixer-ses-limites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/karoslittlecorner.com\/"},{"@type":"ListItem","position":2,"name":"Savoir fixer ses limites"}]},{"@type":"WebSite","@id":"https:\/\/karoslittlecorner.com\/#website","url":"https:\/\/karoslittlecorner.com\/","name":"karoslittlecorner","description":"Karo&#039;s blog","publisher":{"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/karoslittlecorner.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909","name":"karoaug","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"karoaug"},"logo":{"@id":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1"},"sameAs":["https:\/\/karoslittlecorner.com"],"url":"https:\/\/karoslittlecorner.com\/index.php\/author\/karoaug\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=2560%2C1707&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=2560%2C1707&ssl=1",2560,1707,false],"thumbnail":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=700%2C467&ssl=1",700,467,true],"1536x1536":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=1536%2C1024&ssl=1",1536,1024,true],"2048x2048":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=2048%2C1365&ssl=1",2048,1365,true],"pixwell_370x250":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?resize=370%2C250&ssl=1",370,250,true],"pixwell_370x250-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?resize=740%2C500&ssl=1",740,500,true],"pixwell_370x250-3x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?resize=1110%2C750&ssl=1",1110,750,true],"pixwell_280x210":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?resize=280%2C210&ssl=1",280,210,true],"pixwell_280x210-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?resize=560%2C420&ssl=1",560,420,true],"pixwell_400x450":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?resize=400%2C450&ssl=1",400,450,true],"pixwell_400x600":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?resize=400%2C600&ssl=1",400,600,true],"pixwell_450x0":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?resize=450%2C300&ssl=1",450,300,true],"pixwell_780x0":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?resize=780%2C520&ssl=1",780,520,true],"pixwell_780x0-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?resize=1600%2C1067&ssl=1",1600,1067,true],"mailpoet_newsletter_max":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/05\/pexels-nataliya-vaitkevich-5712833-scaled.webp?fit=1320%2C880&ssl=1",1320,880,true]},"uagb_author_info":{"display_name":"karoaug","author_link":"https:\/\/karoslittlecorner.com\/index.php\/author\/karoaug\/"},"uagb_comment_info":11,"uagb_excerpt":"Bonjour \u00e0 tous et bienvenue sur mon blog. Le mois de mai est enfin termin\u00e9 et en un clin d\u2019oeil, nous avons atteint la moiti\u00e9 de l\u2019ann\u00e9e. Ce n\u2019est pas croyable. Etes-vous satisfaits de ce que vous avez accompli jusqu\u2019\u00e0 maintenant? Quelle que soit la r\u00e9ponse \u00e0 cette question, je veux que vous sachiez que&hellip;","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/3343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/comments?post=3343"}],"version-history":[{"count":32,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/3343\/revisions"}],"predecessor-version":[{"id":3383,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/3343\/revisions\/3383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/media\/3311"}],"wp:attachment":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/media?parent=3343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/categories?post=3343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/tags?post=3343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}