{"id":836,"date":"2021-01-28T15:02:33","date_gmt":"2021-01-28T20:02:33","guid":{"rendered":"https:\/\/karoslittlecorner.wordpress.com\/?p=836"},"modified":"2023-02-13T15:44:08","modified_gmt":"2023-02-13T15:44:08","slug":"vise-et-marque","status":"publish","type":"post","link":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/","title":{"rendered":"Vise et marque"},"content":{"rendered":"\r\n<p class=\"has-text-align-center\" style=\"text-align: center;\"><em><strong>Hello Hello; Bonjour et bienvenue sur mon blog. J\u2019esp\u00e8re que tout le monde va bien et puisque c\u2019est mon premier article pour la nouvelle ann\u00e9e, bonne ann\u00e9e \u00e0 tous. Que cette nouvelle ann\u00e9e soit remplie de joie, d\u2019opportunit\u00e9s, de succ\u00e8s et de sant\u00e9. Merci beaucoup de m\u2019accompagner tout au long de ce voyage. Je vous aime et je vous promets de vous rendre fiers chaque jour.<\/strong><\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">La semaine derni\u00e8re, j\u2019ai v\u00e9cu quelque chose avec les enfants au travail et cela m\u2019a inspir\u00e9 de r\u00e9diger cet article. Apr\u00e8s le cong\u00e9 de fin d\u2019ann\u00e9e, tout le monde est retourn\u00e9 \u00e0 l\u2019\u00e9cole heureux et relax\u00e9. J\u2019ai d\u00e9cid\u00e9 de passer du temps avec les enfants et de faire une petite exp\u00e9rience. En gros, je suis pass\u00e9e dans les salles de classe et j\u2019ai eu une conversation avec elles o\u00f9 j\u2019ai demand\u00e9 \u00e0 chacune de partager avec moi 3 objectifs qu\u2019elle s\u2019\u00e9tait fix\u00e9 pour la nouvelle ann\u00e9e. \u00c0 ma grande surprise, je n\u2019ai pas trouv\u00e9 une \u00e9l\u00e8ve qui avait 3 objectifs bien d\u00e9finis \u2026. Certaines n\u2019avaient aucun objectif. \u00c0 la fin de la semaine, seuls 3 enfants sur un effectif de 187 avaient 3 bons objectifs bien pens\u00e9s et clairement d\u00e9finis. Cette exp\u00e9rience a suscit\u00e9 mon int\u00e9r\u00eat pour le sujet d\u2019aujourd\u2019hui.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">Comme je l\u2019ai pr\u00e9cis\u00e9 dans mes pr\u00e9c\u00e9dents articles, j\u2019aime beaucoup accorder priorit\u00e9 \u00e0 la planification de mes activit\u00e9s. Je planifie chaque chose que je fais. C\u2019est pourquoi je d\u00e9teste les plans\/actions de derni\u00e8re minute. Par exemple quelqu\u2019un pourrait me dire qu\u2019il a deux billets pour un spectacle incroyable plus tard et veut que je l\u2019accompagne, je trouverai une excuse pour ne pas y aller parce que je n\u2019ai pas eu le temps de planifier. J\u2019ai donc essay\u00e9 d\u2019expliquer aux enfants pourquoi il \u00e9tait important d\u2019avoir des objectifs pour l\u2019ann\u00e9e et j\u2019\u00e9tais si heureuse de voir leurs petits visages s\u2019illuminer d\u2019admiration alors qu\u2019elles me regardaient parler. Elles ont promis de trouver 3 objectifs qu\u2019elles partageraient avec moi tout au long de l\u2019ann\u00e9e. Je sais que mes enfants ne sont pas les seules \u00e0 ne pas avoir d\u2019objectifs clairement d\u00e9finis pour l\u2019ann\u00e9e. Je pourrais faire la m\u00eame exp\u00e9rience avec mes amis et ma famille et les r\u00e9sultats pourraient \u00eatre tout aussi choquants. Voici donc un article pour vous aider \u00e0 comprendre pourquoi il est important de se fixer des objectifs.<\/p>\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-full\" style=\"text-align: justify;\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-841 size-full\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/d25a5386a9b98132b32e0833d742ba0b7130440332046442936.jpg?resize=736%2C736&ssl=1\" alt=\"\" width=\"736\" height=\"736\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/d25a5386a9b98132b32e0833d742ba0b7130440332046442936.jpg?w=736&ssl=1 736w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/d25a5386a9b98132b32e0833d742ba0b7130440332046442936.jpg?resize=300%2C300&ssl=1 300w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/d25a5386a9b98132b32e0833d742ba0b7130440332046442936.jpg?resize=150%2C150&ssl=1 150w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/d25a5386a9b98132b32e0833d742ba0b7130440332046442936.jpg?resize=88%2C88&ssl=1 88w\" sizes=\"(max-width: 736px) 100vw, 736px\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n<p class=\"has-text-align-center\" style=\"text-align: justify;\"><em><strong>Qu\u2019est-ce qu\u2019un \u00abobjectif <\/strong><\/em>\u00bb?<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">Comme vous le savez tous, j\u2019aime \u00e9duquer les gens sur les termes que j\u2019utilise dans mes articles. <em>Un objectif est une id\u00e9e du futur ou du r\u00e9sultat souhait\u00e9 qu\u2019une personne ou un groupe de personnes envisage, planifie et s\u2019engage \u00e0 atteindre<\/em> (extrait du livre \u00abUne th\u00e9orie de l\u2019\u00e9tablissement d\u2019objectifs et de l\u2019ex\u00e9cution des t\u00e2ches\u00bb). En bref, un objectif est quelque chose que vous voulez r\u00e9aliser, une cible que vous voulez atteindre. C\u2019est le r\u00e9sultat final d\u2019un processus. Il est important d\u2019avoir des objectifs, mais il est \u00e9galement important de savoir ce que vous allez faire pour les atteindre.<\/p>\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-full\" style=\"text-align: justify;\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-846 size-medium\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/citation-objectif4522175130062455883.png?resize=300%2C251&ssl=1\" alt=\"\" width=\"300\" height=\"251\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/citation-objectif4522175130062455883.png?resize=300%2C251&ssl=1 300w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/citation-objectif4522175130062455883.png?resize=768%2C644&ssl=1 768w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/citation-objectif4522175130062455883.png?resize=900%2C754&ssl=1 900w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/citation-objectif4522175130062455883.png?w=940&ssl=1 940w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><em><strong>Pourquoi est-il important de se fixer des objectifs? <\/strong><\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>1. Les objectifs sont une source de motivation<\/strong>. Lorsque vous d\u00e9finissez vos objectifs, votre priorit\u00e9 num\u00e9ro un est de les atteindre. Pour ce faire, il existe une liste de choses \u00e0 prendre en compte. Celui qui a des objectifs est automatiquement plus motiv\u00e9. Sans objectifs nous n\u2019avons pas besoin d\u2019\u00eatre motiv\u00e9s car il n\u2019y a rien \u00e0 r\u00e9aliser. Par exemple, un enfant m\u2019a dit que son objectif pour l\u2019ann\u00e9e \u00e9tait d\u2019acheter tous les produits de la gamme Cantu avec son propre argent. Elle est une \u00e9coli\u00e8re, donc elle n\u2019a pas de salaire, mais avec son objectif en t\u00eate, elle sera motiv\u00e9e \u00e0 \u00e9conomiser de l\u2019argent \u00e0 partir de ce que ses parents lui donnent jusqu\u2019\u00e0 ce qu\u2019elle atteigne son but.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>2. Les objectifs vous aident \u00e0 vous concentrer<\/strong>. Nous avons tendance \u00e0 nous ennuyer facilement. Parfois, nous essayons tellement de rester concentr\u00e9s mais nous finissons par l\u00e2cher prise. Il n\u2019est pas non plus facile de se concentrer sur tout ce que nous faisons en m\u00eame temps. Nos objectifs nous aident \u00e0 nous concentrer car lorsque nous avons un objectif, nous nous concentrons sur les prochaines \u00e9tapes \u00e0 atteindre et cette attention nous maintient dans la bonne direction.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>3. Les objectifs vous aident \u00e0 trouver le sens de votre vie<\/strong>. Comme je l\u2019ai dit \u00e0 mes \u00e9l\u00e8ves, sans objectifs, nous sommes comme un tas de zombies ou un tas de machines d\u00e9pourvues de moteur et notre vie devient une routine. Chaque jour, nous nous r\u00e9veillons et faisons la m\u00eame chose encore et encore. Nous n\u2019avons m\u00eame pas de raison de vivre dans ce cas. Lorsque vous vous fixez des objectifs, vous savez exactement ce que vous voulez dans la vie et quelqu\u2019un qui sait ce qu\u2019il veut est plus susceptible et apte \u00e0 r\u00e9ussir. \u00ab<em>C\u2019est donc le fait de se fixer, d\u2019atteindre et de surpasser des objectifs qui rend la vie meilleure <\/em>\u00bb.<\/p>\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-full\" style=\"text-align: justify;\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-843 size-full\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/042717351564981331231614.jpg?resize=500%2C350&ssl=1\" alt=\"\" width=\"500\" height=\"350\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/042717351564981331231614.jpg?w=500&ssl=1 500w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/042717351564981331231614.jpg?resize=300%2C210&ssl=1 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>4. Les objectifs aident \u00e0 combattre la procrastination<\/strong>. Notre attitude dans la vie est motiv\u00e9e par notre empressement \u00e0 atteindre nos objectifs. Nous procrastinons tous de temps en temps, moi y compris. Cependant, lorsque vous souhaitez r\u00e9aliser quelque chose en peu de temps, vous vous rendez compte que la procrastination repr\u00e9sente un vrai danger. Je peux utiliser mon exp\u00e9rience avec le blog pour vous aider \u00e0 comprendre. J\u2019ai un objectif qui est d\u2019\u00e9crire un article tous les mois ou deux articles par mois. Peu importe \u00e0 quel point je suis fatigu\u00e9e et quel que soit mon niveau de procrastination, mon d\u00e9sir d\u2019atteindre cet objectif prend toujours le dessus et je livre continuellement un combat contre la procrastination. Sans cet objectif, je resterais au lit et regarderais des s\u00e9ries\/feuilletons.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>5. Les objectifs attirent la confiance en soi.<\/strong> C\u2019est assez simple. Nous sommes tous heureux lorsque nous r\u00e9alisons quelque chose, aussi insignifiante soit-elle. Par cons\u00e9quent, lorsque nous atteignons nos objectifs, cela renforce automatiquement notre estime de soi.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">Comme vous pouvez le constater, le titre de cet article ne correspond pas au contenu de l\u2019article. \u00abVise et marque\u00bb, le but de la fixation des objectifs est de pouvoir r\u00e9aliser quelque chose ou simplement suivre un r\u00eave. Lorsque vous d\u00e9finissez vos objectifs, vous visez quelque chose et la r\u00e9alisation de ces objectifs \u00e9quivaut au fait de marquer des buts au football, ce qui explique le titre. N\u2019oubliez pas de toujours viser plus haut. Vous ne marquerez peut-\u00eatre pas aujourd\u2019hui, mais vous le ferez un jour. \u00ab<em>N\u2019ayez pas peur de viser la lune. M\u00eame si vous la manquez, vous atterrirez parmi les \u00e9toile<\/em>s \u00bb.<\/p>\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-full\" style=\"text-align: justify;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-842 size-full\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/2147-600x4204085644001037431807-1.jpg?resize=600%2C420&ssl=1\" alt=\"\" width=\"600\" height=\"420\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/2147-600x4204085644001037431807-1.jpg?w=600&ssl=1 600w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/2147-600x4204085644001037431807-1.jpg?resize=300%2C210&ssl=1 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n<p class=\"has-text-align-center\" style=\"text-align: center;\"><em><strong>C\u2019est tout pour aujourd\u2019hui. J\u2019esp\u00e8re vraiment que vous avez appr\u00e9ci\u00e9 l\u2019article et si vous ne l\u2019avez pas d\u00e9j\u00e0 fait, veuillez trouver au moins trois objectifs pour cette nouvelle ann\u00e9e. \u00c9crivez-les quelque part o\u00f9 vous pourrez les voir tous les matins et vous serez donc motiv\u00e9 pour les r\u00e9aliser. Se fixer des objectifs est vraiment important, essayez-le et remerciez-moi plus tard. Jusqu\u2019\u00e0 ce que nous nous revoyions, restez en s\u00e9curit\u00e9 et soyez b\u00e9nis\u2026. toujours!<\/strong><\/em><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Hello Hello; Bonjour et bienvenue sur mon blog. J\u2019esp\u00e8re que tout le monde va bien et puisque c\u2019est mon premier article pour la nouvelle ann\u00e9e, bonne ann\u00e9e \u00e0 tous. Que cette nouvelle ann\u00e9e soit remplie de joie, d\u2019opportunit\u00e9s, de succ\u00e8s et de sant\u00e9. Merci beaucoup de m\u2019accompagner tout au long de ce voyage. Je vous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":{"0":"post-836","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-traduction-francaise"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vise et marque -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vise et marque -\" \/>\n<meta property=\"og:description\" content=\"Hello Hello; Bonjour et bienvenue sur mon blog. J\u2019esp\u00e8re que tout le monde va bien et puisque c\u2019est mon premier article pour la nouvelle ann\u00e9e, bonne ann\u00e9e \u00e0 tous. Que cette nouvelle ann\u00e9e soit remplie de joie, d\u2019opportunit\u00e9s, de succ\u00e8s et de sant\u00e9. Merci beaucoup de m\u2019accompagner tout au long de ce voyage. Je vous [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-28T20:02:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-13T15:44:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1947\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"karoaug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"karoaug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/01\\\/28\\\/vise-et-marque\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/01\\\/28\\\/vise-et-marque\\\/\"},\"author\":{\"name\":\"karoaug\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"headline\":\"Vise et marque\",\"datePublished\":\"2021-01-28T20:02:33+00:00\",\"dateModified\":\"2023-02-13T15:44:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/01\\\/28\\\/vise-et-marque\\\/\"},\"wordCount\":1218,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"image\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/01\\\/28\\\/vise-et-marque\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/pexels-mong-mong-3351270-scaled.webp?fit=2560%2C1947&ssl=1\",\"articleSection\":[\"Traduction fran\u00e7aise\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/01\\\/28\\\/vise-et-marque\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/01\\\/28\\\/vise-et-marque\\\/\",\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/01\\\/28\\\/vise-et-marque\\\/\",\"name\":\"Vise et marque -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/01\\\/28\\\/vise-et-marque\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/01\\\/28\\\/vise-et-marque\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/pexels-mong-mong-3351270-scaled.webp?fit=2560%2C1947&ssl=1\",\"datePublished\":\"2021-01-28T20:02:33+00:00\",\"dateModified\":\"2023-02-13T15:44:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/01\\\/28\\\/vise-et-marque\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/01\\\/28\\\/vise-et-marque\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/01\\\/28\\\/vise-et-marque\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/pexels-mong-mong-3351270-scaled.webp?fit=2560%2C1947&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/pexels-mong-mong-3351270-scaled.webp?fit=2560%2C1947&ssl=1\",\"width\":2560,\"height\":1947},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/01\\\/28\\\/vise-et-marque\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/karoslittlecorner.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vise et marque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#website\",\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/\",\"name\":\"karoslittlecorner\",\"description\":\"Karo&#039;s blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/karoslittlecorner.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\",\"name\":\"karoaug\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"karoaug\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\"},\"sameAs\":[\"https:\\\/\\\/karoslittlecorner.com\"],\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/author\\\/karoaug\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vise et marque -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/","og_locale":"en_US","og_type":"article","og_title":"Vise et marque -","og_description":"Hello Hello; Bonjour et bienvenue sur mon blog. J\u2019esp\u00e8re que tout le monde va bien et puisque c\u2019est mon premier article pour la nouvelle ann\u00e9e, bonne ann\u00e9e \u00e0 tous. Que cette nouvelle ann\u00e9e soit remplie de joie, d\u2019opportunit\u00e9s, de succ\u00e8s et de sant\u00e9. Merci beaucoup de m\u2019accompagner tout au long de ce voyage. Je vous [&hellip;]","og_url":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/","article_published_time":"2021-01-28T20:02:33+00:00","article_modified_time":"2023-02-13T15:44:08+00:00","og_image":[{"width":2560,"height":1947,"url":"https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp","type":"image\/jpeg"}],"author":"karoaug","twitter_card":"summary_large_image","twitter_misc":{"Written by":"karoaug","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/#article","isPartOf":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/"},"author":{"name":"karoaug","@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"headline":"Vise et marque","datePublished":"2021-01-28T20:02:33+00:00","dateModified":"2023-02-13T15:44:08+00:00","mainEntityOfPage":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/"},"wordCount":1218,"commentCount":0,"publisher":{"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"image":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?fit=2560%2C1947&ssl=1","articleSection":["Traduction fran\u00e7aise"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/","url":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/","name":"Vise et marque -","isPartOf":{"@id":"https:\/\/karoslittlecorner.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/#primaryimage"},"image":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?fit=2560%2C1947&ssl=1","datePublished":"2021-01-28T20:02:33+00:00","dateModified":"2023-02-13T15:44:08+00:00","breadcrumb":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/#primaryimage","url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?fit=2560%2C1947&ssl=1","contentUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?fit=2560%2C1947&ssl=1","width":2560,"height":1947},{"@type":"BreadcrumbList","@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/01\/28\/vise-et-marque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/karoslittlecorner.com\/"},{"@type":"ListItem","position":2,"name":"Vise et marque"}]},{"@type":"WebSite","@id":"https:\/\/karoslittlecorner.com\/#website","url":"https:\/\/karoslittlecorner.com\/","name":"karoslittlecorner","description":"Karo&#039;s blog","publisher":{"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/karoslittlecorner.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909","name":"karoaug","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"karoaug"},"logo":{"@id":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1"},"sameAs":["https:\/\/karoslittlecorner.com"],"url":"https:\/\/karoslittlecorner.com\/index.php\/author\/karoaug\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?fit=2560%2C1947&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?fit=2560%2C1947&ssl=1",2560,1947,false],"thumbnail":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?fit=300%2C228&ssl=1",300,228,true],"medium_large":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?fit=768%2C584&ssl=1",768,584,true],"large":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?fit=700%2C533&ssl=1",700,533,true],"1536x1536":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?fit=1536%2C1168&ssl=1",1536,1168,true],"2048x2048":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?fit=2048%2C1558&ssl=1",2048,1558,true],"pixwell_370x250":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?resize=370%2C250&ssl=1",370,250,true],"pixwell_370x250-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?resize=740%2C500&ssl=1",740,500,true],"pixwell_370x250-3x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?resize=1110%2C750&ssl=1",1110,750,true],"pixwell_280x210":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?resize=280%2C210&ssl=1",280,210,true],"pixwell_280x210-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?resize=560%2C420&ssl=1",560,420,true],"pixwell_400x450":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?resize=400%2C450&ssl=1",400,450,true],"pixwell_400x600":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?resize=400%2C600&ssl=1",400,600,true],"pixwell_450x0":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?resize=450%2C342&ssl=1",450,342,true],"pixwell_780x0":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?resize=780%2C593&ssl=1",780,593,true],"pixwell_780x0-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?resize=1600%2C1217&ssl=1",1600,1217,true],"mailpoet_newsletter_max":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/01\/pexels-mong-mong-3351270-scaled.webp?fit=1320%2C1004&ssl=1",1320,1004,true]},"uagb_author_info":{"display_name":"karoaug","author_link":"https:\/\/karoslittlecorner.com\/index.php\/author\/karoaug\/"},"uagb_comment_info":20,"uagb_excerpt":"Hello Hello; Bonjour et bienvenue sur mon blog. J\u2019esp\u00e8re que tout le monde va bien et puisque c\u2019est mon premier article pour la nouvelle ann\u00e9e, bonne ann\u00e9e \u00e0 tous. Que cette nouvelle ann\u00e9e soit remplie de joie, d\u2019opportunit\u00e9s, de succ\u00e8s et de sant\u00e9. Merci beaucoup de m\u2019accompagner tout au long de ce voyage. Je vous&hellip;","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/comments?post=836"}],"version-history":[{"count":3,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/836\/revisions"}],"predecessor-version":[{"id":2616,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/836\/revisions\/2616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/media\/2615"}],"wp:attachment":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/media?parent=836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/categories?post=836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/tags?post=836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}