{"id":987,"date":"2021-07-17T13:18:44","date_gmt":"2021-07-17T17:18:44","guid":{"rendered":"https:\/\/karoslittlecorner.wordpress.com\/?p=987"},"modified":"2023-02-13T15:43:14","modified_gmt":"2023-02-13T15:43:14","slug":"10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine","status":"publish","type":"post","link":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/","title":{"rendered":"10 choses importantes que j&#8217;ai apprises jusqu&#8217;\u00e0 pr\u00e9sent dans ma vingtaine"},"content":{"rendered":"\r\n<p class=\"has-text-align-center\" style=\"text-align: center;\"><em><strong>Bonjour \u00e0 tous et bienvenue sur mon blog. J\u2019esp\u00e8re que vous allez bien. J\u2019ai attendu l\u2019\u00e9t\u00e9 toute l\u2019ann\u00e9e avec impatience et maintenant que l\u2019\u00e9t\u00e9 est l\u00e0, COVID a d\u00e9cid\u00e9 de faire une r\u00e9apparition. Nous assistons \u00e0 une nouvelle vague ici en Ha\u00efti et si la derni\u00e8re ne nous a pas durement touch\u00e9s, celle-ci est arriv\u00e9e de plein fouet. Quoi qu\u2019il en soit, COVID ou pas, je dois rester productive et c\u2019est pourquoi aujourd\u2019hui je viens avec un nouvel article.<\/strong><\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\">Si comme moi vous \u00eates dans la vingtaine, je suis s\u00fbre que vous vous \u00eates d\u00e9j\u00e0 demand\u00e9 : \u00ab Qu\u2019est-ce que je fais? \u00bb \u00ab Suis-je o\u00f9 j\u2019\u00e9tais cens\u00e9 \u00eatre ? \u00bb \u00ab Qu\u2019est-ce qui se passe? \u00bb \u2026. Beaucoup de questions auxquelles personne ne peut vraiment r\u00e9pondre. \u00catre dans la vingtaine c\u2019est \u00eatre constamment dans une bataille contre soi-m\u00eame et contre le monde. Vous vous sentez perdu et vous ne savez pas quelles \u00e9tapes vous \u00eates cens\u00e9 franchir ensuite. Je ne sais pas comment c\u2019\u00e9tait pour les g\u00e9n\u00e9rations pr\u00e9c\u00e9dentes, mais quand je regarde autour de moi, je peux voir que beaucoup d\u2019entre nous, dans ma g\u00e9n\u00e9ration sont en difficult\u00e9. Aujourd\u2019hui, je vais \u00e9num\u00e9rer certaines choses que j\u2019ai apprises et que j\u2019apprends encore au cours de ce cheminement vers l\u2019\u00e2ge adulte.<\/p>\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-medium is-resized\" style=\"text-align: justify;\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-989 size-medium\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/img_5066.jpg?resize=300%2C263&ssl=1\" alt=\"\" width=\"300\" height=\"263\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/img_5066.jpg?resize=300%2C263&ssl=1 300w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/img_5066.jpg?resize=768%2C674&ssl=1 768w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/img_5066.jpg?resize=900%2C789&ssl=1 900w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/img_5066.jpg?w=960&ssl=1 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>1. D\u00e9finissez toujours vos priorit\u00e9s. <\/strong>Si vous \u00eates proche de moi alors vous savez que je r\u00e9p\u00e8te souvent \u00e7a. Quoi que vous fassiez dans la vie, vos priorit\u00e9s doivent \u00eatre claires et nettes. Quand j\u2019\u00e9tais plus jeune, ma m\u00e8re disait tout le temps : \u201cMaintenant, ta priorit\u00e9 devrait \u00eatre tes \u00e9tudes, tu auras du temps pour autre chose apr\u00e8s\u201d. Je d\u00e9testais quand elle disait \u00e7a parce que j\u2019avais l\u2019impression d\u2019\u00eatre prise au pi\u00e8ge et que je ne pouvais pas m\u2019amuser, mais maintenant je la comprends mieux. Si vous n\u2019avez pas de priorit\u00e9s, il vous sera difficile d\u2019atteindre vos objectifs. Vous vous perdrez en essayant de faire plusieurs choses en m\u00eame temps. \u201cQui trop embrasse mal \u00e9treint\u201d<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>2. C\u2019est normal de se sentir perdu.<\/strong> Je ne peux pas compter le nombre de fois o\u00f9 j\u2019ai \u00e9clat\u00e9 en sanglots parce que je ne comprenais pas ce qui se passait. Certaines fois, j\u2019avais l\u2019impression que le temps passait si vite et je ne savais pas quoi faire pour l\u2019arr\u00eater (je me sens toujours comme \u00e7a). Apr\u00e8s avoir obtenu votre dipl\u00f4me d\u2019\u00e9tudes secondaires, vous savez que votre prochaine \u00e9tape est l\u2019universit\u00e9, mais lorsque vous bouclez vos \u00e9tudes universitaires vous vous rendez compte que personne ne vous a pr\u00e9par\u00e9 pour cette \u00e9tape de la vie. Que suis-je cens\u00e9e faire maintenant ? C\u2019est \u00e0 ce moment-l\u00e0 que vous commencez \u00e0 remettre en question vos r\u00e9alisations et vos aptitudes : \u00ab Est-ce que je r\u00e9ussirai un jour ? \u00bb M\u00eame si vous vous sentez perdu et que vous ne savez pas quoi faire ensuite : Pas de panique !! Si vous \u00eates croyant, priez et demandez \u00e0 Dieu de vous montrer le chemin. Comme je le mentionne toujours dans mes articles, la vie ne nous a pas procur\u00e9 un livre manuel nous dictant ce qu\u2019on doit faire \u00e0 chaque \u00e9tape. Nous savons seulement ce qui est mal et ce qui est bien. Commettre des erreurs c\u2019est normal. Malcom Forbes a dit un jour :<em> \u00ab L\u2019\u00e9chec est un succ\u00e8s si nous en tirons les le\u00e7ons \u00bb. <\/em>L\u2019\u00e9chec n\u2019est pas la fin. Vous \u00eates plus fort que les difficult\u00e9s que vous rencontrez.<\/p>\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-full\" style=\"text-align: justify;\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-990 size-full\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/1271dee9-1079-4831-b50a-95a78483b141.jpg?resize=828%2C779&ssl=1\" alt=\"\" width=\"828\" height=\"779\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/1271dee9-1079-4831-b50a-95a78483b141.jpg?w=828&ssl=1 828w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/1271dee9-1079-4831-b50a-95a78483b141.jpg?resize=300%2C282&ssl=1 300w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/1271dee9-1079-4831-b50a-95a78483b141.jpg?resize=768%2C723&ssl=1 768w\" sizes=\"(max-width: 828px) 100vw, 828px\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>3. Commencez \u00e0 dire non<\/strong>. J\u2019ai eu du mal \u00e0 accepter que tout le monde n\u2019ait pas un grand c\u0153ur comme moi. A l\u2019universit\u00e9, je faisais toujours le travail des autres. Il m\u2019\u00e9tait presque impossible de dire non (j\u2019ai toujours cette difficult\u00e9 pour \u00eatre honn\u00eate). J\u2019avais des amis qui \u00e9taient dans d\u2019autres universit\u00e9s, mais je r\u00e9digeais quand m\u00eame des devoirs pour eux. Quand on arrive dans la vingtaine,il faut commencer \u00e0 penser \u00e0 soi. Il y aura toujours des gens \u00e0 vous demander de les aider avec certaines choses et quand vous direz non, ils prieront pour votre \u00e9chec. Parfois, ces personnes sont plus proches de vous que vous ne le pensez. Ne vous m\u00e9prenez pas, c\u2019est bien d\u2019aider les autres, mais vous devez savoir quand vous arr\u00eater pour pouvoir vous concentrer sur vous-m\u00eame. Vous devez \u00e9galement \u00eatre en mesure de dire non lorsque les gens vous entra\u00eenent dans la mauvaise direction.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>4. Demandez de l\u2019aide. <\/strong>\u00ab <em>Si tu veux aller vite, vas-y seul ; mais si tu veux aller loin, marchons ensemble \u00bb. <\/em>Que cela vous plaise ou non, vous aurez toujours besoin de gens \u00e0 c\u00f4t\u00e9 de vous pour r\u00e9ussir. Ne laissez pas votre ego vous contr\u00f4ler, si vous avez besoin d\u2019aide, demandez-en. Il y aura toujours des gens pr\u00eats \u00e0 vous aider.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>5. Acceptez que tout se passe pour une raison. <\/strong>Bien que certaines personnes soient toujours en d\u00e9saccord quand je dis cela, mais dans la vie, tout se passe pour une raison bien pr\u00e9cise. Peut-\u00eatre que vous n\u2019avez pas obtenu ce travail parce que quelque part ailleurs, un meilleur emploi vous attend. C\u2019est pourquoi il est important de toujours pers\u00e9v\u00e9rer. M\u00eame si vous tombez fort, assurez-vous de rebondir 10 fois plus haut. Tout ce qui se passe dans nos vies est une le\u00e7on, que cela apporte du bonheur ou de la tristesse. Ce qui compte, c\u2019est comment nous allons nous en remettre, comment nous allons utiliser cette exp\u00e9rience pour grandir et devenir une meilleure personne.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>6. Placez toujours votre bonheur en premier.<\/strong> Sur les dix points \u00e9voqu\u00e9s dans cet article , c\u2019est pour moi la chose la plus importante. Toute ma vie, j\u2019ai toujours pris en consid\u00e9ration les sentiments des autres avant de prendre une d\u00e9cision. Que ce soit avec des amis ou des membres de ma famille. Si je sais que ma d\u00e9cision peut les blesser, j\u2019abandonnerais litt\u00e9ralement et ne le ferais pas m\u00eame si je serais moi-m\u00eame bless\u00e9e dans le processus. Malheureusement, j\u2019ai d\u00fb apprendre \u00e0 mes d\u00e9pens que je ne devais jamais attendre la validation des autres. Les gens feront toujours ce qui est le mieux pour eux, peu importe ce que je ressens et il est temps que je commence \u00e0 faire de m\u00eame. Si vous voulez abandonner quelque chose qui pourrait vous rendre heureux simplement parce que cela pourrait potentiellement blesser d\u2019autres personnes dans le processus, prenez une minute et demandez-vous si ces personnes auraient fait la m\u00eame chose pour vous. Si la r\u00e9ponse est non, alors faites-le et faites-le sans regret. En fin de compte, votre bonheur devrait \u00eatre votre priorit\u00e9 num\u00e9ro un.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>7. Commencez \u00e0 \u00e9conomiser de l\u2019argent. <\/strong>La vingtaine repr\u00e9sente les ann\u00e9es les plus importantes de votre vie car c\u2019est \u00e0 ce moment-l\u00e0 que vous commencez \u00e0 vous pr\u00e9parer \u00e0 l\u2019\u00e2ge adulte. Une fois que vous commencez \u00e0 gagner de l\u2019argent, vous devez \u00e9tablir un plan sur la fa\u00e7on dont vous allez \u00e9conomiser cet argent. Vous aurez besoin d\u2019argent pour \u00eatre totalement ind\u00e9pendant, pour acheter une maison par exemple ou pour faire face \u00e0 des situations inattendues comme des urgences. Les parents vieillissent et ils ne seront pas toujours l\u00e0 pour subvenir \u00e0 nos besoins. Vous allez fonder une famille et il va falloir subvenir aux besoins. L\u2019argent va et vient. Vous pouvez passer un mois \u00e0 essayer de gagner de l\u2019argent et il dispara\u00eet en un jour. La meilleure chose \u00e0 faire est d\u2019avoir un compte d\u2019\u00e9pargne et d\u2019y mettre le plus que possible \u00e0 chaque fois qu\u2019on en gagne.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>8. Vous perdrez certainement des amis. <\/strong>Les gens changent\u2026. et quand \u00e7a arrive on se rend compte qu\u2019il y a des gens dont on n\u2019a plus besoin dans notre vie, non pas parce qu\u2019on les d\u00e9teste mais parce qu\u2019on finit par r\u00e9aliser qu\u2019on ne va plus dans la m\u00eame direction. J\u2019ai perdu plus d\u2019amis dans la vingtaine qu\u2019au cours des 19 ann\u00e9es pr\u00e9c\u00e9dentes. Certains apr\u00e8s des disputes et d\u2019autres ont disparu juste comme \u00e7a. Pour certaines de ces amiti\u00e9s, je me suis sentie bless\u00e9e et trahie , mais pour d\u2019autres, j\u2019ai simplement accept\u00e9 que c\u2019\u00e9tait pour le mieux. La vie est comme une camionnette, certaines personnes commencent le trajet avec vous, descendent \u00e0 mi-chemin pour faire place \u00e0 d\u2019autres qui montent pendant le trajet. Vous n\u2019arriverez probablement pas \u00e0 destination avec ceux qui ont commenc\u00e9 avec vous. C\u2019est vraiment difficile d\u2019accepter \u00e7a parce que vous devez abandonner certaines personnes que vous pensiez jouer un grand r\u00f4le dans votre vie, mais vous rencontrerez \u00e9galement des personnes qui auront une place significative dans votre c\u0153ur et votre vie.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>9. Ne perdez pas de temps<\/strong>. Le temps est notre ressource la plus pr\u00e9cieuse comme on dit tout le temps. C\u2019est la seule chose que vous ne pouvez pas r\u00e9cup\u00e9rer, peu importe vos efforts. Dans la vingtaine, vous \u00eates cens\u00e9 profiter de la vie, mais vous devez \u00e9galement faire attention \u00e0 ne pas perdre votre temps \u00e0 faire les mauvaises choses. Si vous voulez r\u00e9ussir, vous devez travailler aussi dur que possible pour atteindre le sommet. Steeve Harvey a dit un jour que les personnes qui ont du succ\u00e8s (les riches) ne dorment pas huit heures par jour. Pendant que vous dormez, quelque part le stock market (bourse) est d\u00e9j\u00e0 ouverte et les gens prennent des d\u00e9cisions concernant votre vie. Dans la vingtaine, vous devriez utiliser votre temps \u00e0 bon escient.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-justify\" style=\"text-align: justify;\"><strong>10. Il faut s\u2019aimer<\/strong>. Celui-ci est explicite. Aimez-vous parce que personne d\u2019autre ne le fera \u00e0 votre place. Prenez soin de vous et visez toujours des choses qui vous rendent heureux tant que cela ne veut pas dire blesser volontairement les gens autour de vous. En fin de compte, votre bonheur devrait \u00eatre au-dessus de tout le reste.<\/p>\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-full\" style=\"text-align: justify;\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"798\" height=\"812\" class=\"wp-image-991 aligncenter\" src=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/17e31b3d-ba91-4550-9c01-baebf926a2d3.jpg?resize=798%2C812&ssl=1\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/17e31b3d-ba91-4550-9c01-baebf926a2d3.jpg?w=798&ssl=1 798w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/17e31b3d-ba91-4550-9c01-baebf926a2d3.jpg?resize=295%2C300&ssl=1 295w, https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/17e31b3d-ba91-4550-9c01-baebf926a2d3.jpg?resize=768%2C781&ssl=1 768w\" sizes=\"(max-width: 798px) 100vw, 798px\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n<p class=\"has-text-align-center\" style=\"text-align: center;\"><em><strong>C\u2019est tout pour aujourd\u2019hui. J\u2019ai commenc\u00e9 \u00e0 \u00e9crire cet article depuis mai, nous sommes d\u00e9j\u00e0 en juillet et je le publie enfin. D\u00e9sol\u00e9 pour l\u2019attente. Merci \u00e0 mes fid\u00e8les lecteurs et lectrices. N\u2019oubliez pas de le partager avec vos amis. En attendant mon prochain article, restez en s\u00e9curit\u00e9 et soyez b\u00e9nis\u2026. Toujours. Bisous bisous!!!<\/strong><\/em><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Bonjour \u00e0 tous et bienvenue sur mon blog. J\u2019esp\u00e8re que vous allez bien. J\u2019ai attendu l\u2019\u00e9t\u00e9 toute l\u2019ann\u00e9e avec impatience et maintenant que l\u2019\u00e9t\u00e9 est l\u00e0, COVID a d\u00e9cid\u00e9 de faire une r\u00e9apparition. Nous assistons \u00e0 une nouvelle vague ici en Ha\u00efti et si la derni\u00e8re ne nous a pas durement touch\u00e9s, celle-ci est arriv\u00e9e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2612,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":{"0":"post-987","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-traduction-francaise"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 choses importantes que j&#039;ai apprises jusqu&#039;\u00e0 pr\u00e9sent dans ma vingtaine -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 choses importantes que j&#039;ai apprises jusqu&#039;\u00e0 pr\u00e9sent dans ma vingtaine -\" \/>\n<meta property=\"og:description\" content=\"Bonjour \u00e0 tous et bienvenue sur mon blog. J\u2019esp\u00e8re que vous allez bien. J\u2019ai attendu l\u2019\u00e9t\u00e9 toute l\u2019ann\u00e9e avec impatience et maintenant que l\u2019\u00e9t\u00e9 est l\u00e0, COVID a d\u00e9cid\u00e9 de faire une r\u00e9apparition. Nous assistons \u00e0 une nouvelle vague ici en Ha\u00efti et si la derni\u00e8re ne nous a pas durement touch\u00e9s, celle-ci est arriv\u00e9e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-17T17:18:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-13T15:43:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"karoaug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"karoaug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/07\\\/17\\\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/07\\\/17\\\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\\\/\"},\"author\":{\"name\":\"karoaug\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"headline\":\"10 choses importantes que j&#8217;ai apprises jusqu&#8217;\u00e0 pr\u00e9sent dans ma vingtaine\",\"datePublished\":\"2021-07-17T17:18:44+00:00\",\"dateModified\":\"2023-02-13T15:43:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/07\\\/17\\\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\\\/\"},\"wordCount\":1717,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"image\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/07\\\/17\\\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=2560%2C1920&ssl=1\",\"articleSection\":[\"Traduction fran\u00e7aise\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/07\\\/17\\\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/07\\\/17\\\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\\\/\",\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/07\\\/17\\\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\\\/\",\"name\":\"10 choses importantes que j'ai apprises jusqu'\u00e0 pr\u00e9sent dans ma vingtaine -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/07\\\/17\\\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/07\\\/17\\\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=2560%2C1920&ssl=1\",\"datePublished\":\"2021-07-17T17:18:44+00:00\",\"dateModified\":\"2023-02-13T15:43:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/07\\\/17\\\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/07\\\/17\\\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/07\\\/17\\\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=2560%2C1920&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=2560%2C1920&ssl=1\",\"width\":2560,\"height\":1920,\"caption\":\"pexels-miesha-renae-maiden-219249\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/2021\\\/07\\\/17\\\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/karoslittlecorner.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 choses importantes que j&#8217;ai apprises jusqu&#8217;\u00e0 pr\u00e9sent dans ma vingtaine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#website\",\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/\",\"name\":\"karoslittlecorner\",\"description\":\"Karo&#039;s blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/karoslittlecorner.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/karoslittlecorner.com\\\/#\\\/schema\\\/person\\\/d9dfd7f8022e34508ae5d9071ee04909\",\"name\":\"karoaug\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"karoaug\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/karoslittlecorner.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1\"},\"sameAs\":[\"https:\\\/\\\/karoslittlecorner.com\"],\"url\":\"https:\\\/\\\/karoslittlecorner.com\\\/index.php\\\/author\\\/karoaug\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 choses importantes que j'ai apprises jusqu'\u00e0 pr\u00e9sent dans ma vingtaine -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/","og_locale":"en_US","og_type":"article","og_title":"10 choses importantes que j'ai apprises jusqu'\u00e0 pr\u00e9sent dans ma vingtaine -","og_description":"Bonjour \u00e0 tous et bienvenue sur mon blog. J\u2019esp\u00e8re que vous allez bien. J\u2019ai attendu l\u2019\u00e9t\u00e9 toute l\u2019ann\u00e9e avec impatience et maintenant que l\u2019\u00e9t\u00e9 est l\u00e0, COVID a d\u00e9cid\u00e9 de faire une r\u00e9apparition. Nous assistons \u00e0 une nouvelle vague ici en Ha\u00efti et si la derni\u00e8re ne nous a pas durement touch\u00e9s, celle-ci est arriv\u00e9e [&hellip;]","og_url":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/","article_published_time":"2021-07-17T17:18:44+00:00","article_modified_time":"2023-02-13T15:43:14+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp","type":"image\/jpeg"}],"author":"karoaug","twitter_card":"summary_large_image","twitter_misc":{"Written by":"karoaug","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/#article","isPartOf":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/"},"author":{"name":"karoaug","@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"headline":"10 choses importantes que j&#8217;ai apprises jusqu&#8217;\u00e0 pr\u00e9sent dans ma vingtaine","datePublished":"2021-07-17T17:18:44+00:00","dateModified":"2023-02-13T15:43:14+00:00","mainEntityOfPage":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/"},"wordCount":1717,"commentCount":4,"publisher":{"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"image":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=2560%2C1920&ssl=1","articleSection":["Traduction fran\u00e7aise"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/","url":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/","name":"10 choses importantes que j'ai apprises jusqu'\u00e0 pr\u00e9sent dans ma vingtaine -","isPartOf":{"@id":"https:\/\/karoslittlecorner.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/#primaryimage"},"image":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=2560%2C1920&ssl=1","datePublished":"2021-07-17T17:18:44+00:00","dateModified":"2023-02-13T15:43:14+00:00","breadcrumb":{"@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/#primaryimage","url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=2560%2C1920&ssl=1","contentUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=2560%2C1920&ssl=1","width":2560,"height":1920,"caption":"pexels-miesha-renae-maiden-219249"},{"@type":"BreadcrumbList","@id":"https:\/\/karoslittlecorner.com\/index.php\/2021\/07\/17\/10-choses-importantes-que-jai-apprises-jusqua-present-dans-ma-vingtaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/karoslittlecorner.com\/"},{"@type":"ListItem","position":2,"name":"10 choses importantes que j&#8217;ai apprises jusqu&#8217;\u00e0 pr\u00e9sent dans ma vingtaine"}]},{"@type":"WebSite","@id":"https:\/\/karoslittlecorner.com\/#website","url":"https:\/\/karoslittlecorner.com\/","name":"karoslittlecorner","description":"Karo&#039;s blog","publisher":{"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/karoslittlecorner.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/karoslittlecorner.com\/#\/schema\/person\/d9dfd7f8022e34508ae5d9071ee04909","name":"karoaug","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"karoaug"},"logo":{"@id":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2023\/01\/cropped-cropped-Karos-little-corner-Logo-2-1-4.png?fit=500%2C500&ssl=1"},"sameAs":["https:\/\/karoslittlecorner.com"],"url":"https:\/\/karoslittlecorner.com\/index.php\/author\/karoaug\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=2560%2C1920&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=2560%2C1920&ssl=1",2560,1920,false],"thumbnail":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=300%2C225&ssl=1",300,225,true],"medium_large":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=768%2C576&ssl=1",768,576,true],"large":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=700%2C525&ssl=1",700,525,true],"1536x1536":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=1536%2C1152&ssl=1",1536,1152,true],"2048x2048":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=2048%2C1536&ssl=1",2048,1536,true],"pixwell_370x250":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?resize=370%2C250&ssl=1",370,250,true],"pixwell_370x250-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?resize=740%2C500&ssl=1",740,500,true],"pixwell_370x250-3x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?resize=1110%2C750&ssl=1",1110,750,true],"pixwell_280x210":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?resize=280%2C210&ssl=1",280,210,true],"pixwell_280x210-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?resize=560%2C420&ssl=1",560,420,true],"pixwell_400x450":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?resize=400%2C450&ssl=1",400,450,true],"pixwell_400x600":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?resize=400%2C600&ssl=1",400,600,true],"pixwell_450x0":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?resize=450%2C338&ssl=1",450,338,true],"pixwell_780x0":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?resize=780%2C585&ssl=1",780,585,true],"pixwell_780x0-2x":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?resize=1600%2C1200&ssl=1",1600,1200,true],"mailpoet_newsletter_max":["https:\/\/i0.wp.com\/karoslittlecorner.com\/wp-content\/uploads\/2021\/07\/pexels-miesha-renae-maiden-219249-scaled.webp?fit=1320%2C990&ssl=1",1320,990,true]},"uagb_author_info":{"display_name":"karoaug","author_link":"https:\/\/karoslittlecorner.com\/index.php\/author\/karoaug\/"},"uagb_comment_info":25,"uagb_excerpt":"Bonjour \u00e0 tous et bienvenue sur mon blog. J\u2019esp\u00e8re que vous allez bien. J\u2019ai attendu l\u2019\u00e9t\u00e9 toute l\u2019ann\u00e9e avec impatience et maintenant que l\u2019\u00e9t\u00e9 est l\u00e0, COVID a d\u00e9cid\u00e9 de faire une r\u00e9apparition. Nous assistons \u00e0 une nouvelle vague ici en Ha\u00efti et si la derni\u00e8re ne nous a pas durement touch\u00e9s, celle-ci est arriv\u00e9e&hellip;","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/comments?post=987"}],"version-history":[{"count":3,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/987\/revisions"}],"predecessor-version":[{"id":2611,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/posts\/987\/revisions\/2611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/media\/2612"}],"wp:attachment":[{"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/media?parent=987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/categories?post=987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/karoslittlecorner.com\/index.php\/wp-json\/wp\/v2\/tags?post=987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}